{"id":9801,"date":"2020-10-06T14:48:03","date_gmt":"2020-10-06T14:48:03","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=9801"},"modified":"2020-10-06T14:48:04","modified_gmt":"2020-10-06T14:48:04","slug":"partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/","title":{"rendered":"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico"},"content":{"rendered":"\n<h2 id=\"h-thomas-partey-ha-expresado-su-agradecimiento-a-la-afici-n-del-club-del-que-form-parte-durante-8-a-os-tras-completar-su-fichaje-por-el-arsenal\">Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.<\/h2>\n\n\n\n<p>En lo que fue una sorpresa para los fan\u00e1ticos del Atl\u00e9tico de Madrid, y tal vez una sorpresa incluso para los fan\u00e1ticos del Arsenal, Thomas Partey complet\u00f3 su cambio a la Premier League en el d\u00eda l\u00edmite de la ventana de transferencia de verano.<\/p>\n\n\n\n<p>El centrocampista defensivo fich\u00f3 por el Atleti a los 18 a\u00f1os en 2011 y fue reclutado por el filial del club.<\/p>\n\n\n\n<p>Ascendiendo de rango, y despu\u00e9s de un par de cesiones, gan\u00f3 un ascenso al primer equipo de Los Rojiblancos en 2015.<\/p>\n\n\n\n<p>Desde entonces, sigui\u00f3 siendo una parte integral del equipo de Diego Simeone, ayud\u00e1ndolos a conseguir triunfos en la Europa League, la Supercopa de la UEFA y guiando al equipo a una final de la Champions League.<\/p>\n\n\n\n<p>El ghan\u00e9s se despidi\u00f3 recientemente del Wanda Metropolitano para apostar por un nuevo reto en el exterior.<\/p>\n\n\n\n<p>\u00abQueridos aficionados del Atl\u00e9tico, hoy solo tengo palabras de agradecimiento para vosotros.\u00a0Desde hace varios a\u00f1os, el Atl\u00e9tico de Madrid ha sido mi hogar y una parte de esta familia siempre estar\u00e1 conmigo,\u00bb escribi\u00f3 Partey en una\u00a0<em><a href=\"https:\/\/www.instagram.com\/p\/CF_ucBwgI5m\/\" target=\"_blank\" rel=\"noreferrer noopener\">publicaci\u00f3n de Instagram<\/a><\/em>\u00a0despu\u00e9s de unirse al Arsenal.<\/p>\n\n\n\n<figure class=\"wp-block-embed-instagram wp-block-embed is-type-rich is-provider-instagram\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CF_ucBwgI5m\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"12\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:640px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CF_ucBwgI5m\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div><\/a> <p style=\" margin:8px 0 0 0; padding:0 4px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CF_ucBwgI5m\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#000; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none; word-wrap:break-word;\" target=\"_blank\">Querida afici\u00f3n rojiblanca, hoy solo tengo palabras de agradecimiento con vosotros. Desde hace ya varios a\u00f1os, el Atl\u00e9tico de Madrid ha sido mi casa y una parte de esta familia siempre estar\u00e1 conmigo. Quiero dar las gracias al club por la confianza depositada en mi desde el primer d\u00eda , pero sobre todo, quiero daros las gracias a vosotros, a esta maravillosa afici\u00f3n que me acepto desde el primer momento y que ha demostrado que est\u00e1 tanto en las buenas como en las malas y que verdaderamente nunca deja de creer. El atl\u00e9tico de Madrid no es solo un club, es una familia. Gracias \u2665\ufe0f<\/a><\/p> <p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\">A post shared by <a href=\"https:\/\/www.instagram.com\/thomaspartey5\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px;\" target=\"_blank\"> Thomas Teye Partey<\/a> (@thomaspartey5) on <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2020-10-06T08:40:22+00:00\">Oct 6, 2020 at 1:40am PDT<\/time><\/p><\/div><\/blockquote><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>\u00abQuiero agradecer al club la confianza depositada en m\u00ed desde el primer d\u00eda, pero sobre todo quiero agradecerles esta maravillosa afici\u00f3n que acept\u00e9 desde el primer momento y que ha demostrado que es tanto en los buenos tiempos como en malos tiempos y nunca dejas de creer realmente.\u00bb<\/p>\n\n\n\n<p>\u00abEl Atl\u00e9tico de Madrid no es solo un club, es una familia.\u00a0Gracias.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.<\/p>\n","protected":false},"author":868,"featured_media":9802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[520,1863,78,77,2928],"enet_tags":{"team":["9825","9906"],"league":["87","47"],"player":["434325"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico<\/title>\n<meta name=\"description\" content=\"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico\" \/>\n<meta property=\"og:description\" content=\"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T14:48:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T14:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg\",\"width\":1024,\"height\":673},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/\",\"name\":\"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#primaryimage\"},\"datePublished\":\"2020-10-06T14:48:03+00:00\",\"dateModified\":\"2020-10-06T14:48:04+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico","description":"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/","og_locale":"es_ES","og_type":"article","og_title":"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico","og_description":"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-10-06T14:48:03+00:00","article_modified_time":"2020-10-06T14:48:04+00:00","og_image":[{"width":1024,"height":673,"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg","width":1024,"height":673},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/","name":"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#primaryimage"},"datePublished":"2020-10-06T14:48:03+00:00","dateModified":"2020-10-06T14:48:04+00:00","author":{"@id":""},"description":"Thomas Partey ha expresado su agradecimiento a la afici\u00f3n del club del que form\u00f3 parte durante 8 a\u00f1os tras completar su fichaje por el Arsenal.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/partey-habla-emocionado-del-mensaje-de-despedida-a-la-aficion-del-atletico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Partey habla emocionado del mensaje de despedida a la afici\u00f3n del Atl\u00e9tico"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/1065935434.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/9801"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/868"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=9801"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/9801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/9802"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=9801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=9801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=9801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}