{"id":9791,"date":"2020-10-06T12:43:46","date_gmt":"2020-10-06T12:43:46","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=9791"},"modified":"2020-10-06T12:43:47","modified_gmt":"2020-10-06T12:43:47","slug":"modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/","title":{"rendered":"Modric explica como el &#8216;incre\u00edble&#8217; Hazard demostrar\u00e1 su val\u00eda en el Real Madrid"},"content":{"rendered":"\n<h2 id=\"h-luka-modric-est-seguro-de-que-eden-hazard-demostrar-que-sus-cr-ticos-del-real-madrid-est-n-equivocados-una-vez-que-se-libere-de-las-lesiones-que-lo-han-frenado\">Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.<\/h2>\n\n\n\n<p>La mudanza so\u00f1ada de Hazard al Real Madrid se convirti\u00f3 r\u00e1pidamente en una pesadilla cuando los problemas de fitness arruinaron su campa\u00f1a de debut, lo que result\u00f3 en solo 22 apariciones en todas las competiciones.<\/p>\n\n\n\n<p>Solo un gol y siete asistencias fueron apenas lo que los fan\u00e1ticos esperaban a cambio de su transferencia de 100 millones de euros del Chelsea.\u00a0Sobre todo porque era el hombre indicado para reactivar el ataque del club y fue avalado por el t\u00e9cnico Zinedine Zidane.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"PlayerCareerStats\" width=\"440\" data-player-id=\"107417\" data-season-id=\"14180\"><\/si-lb-widget><\/div>\n\n\n\n<p>Las lesiones han seguido siendo un problema esta temporada, y&nbsp;<em><a href=\"https:\/\/acefootball.com\/football-news\/again-eden-hazard-suffers-another-setback-at-real-madrid\/\">Hazard tuvo que retirarse de la victoria por 1-0 de la semana pasada sobre el Valladolid<\/a><\/em>&nbsp;debido a una lesi\u00f3n muscular.&nbsp;Probablemente no estar\u00e1 disponible durante unas tres o cuatro semanas.<\/p>\n\n\n\n<p>Sin embargo, Modric espera que el jugador de 29 a\u00f1os sea bueno y demuestre que sus esc\u00e9pticos est\u00e1n equivocados.<\/p>\n\n\n\n<p>\u00abNo es una situaci\u00f3n c\u00f3moda para Hazard,\u00bb dijo el mediapunta del Real Madrid a\u00a0<em><a href=\"https:\/\/www.cope.es\/deportes\/futbol\/noticias\/noticia-entrevista-modric-partidazo-cope-05-10-20-20201005_928925\" target=\"_blank\" rel=\"noreferrer noopener\">El Partidazo de Cope<\/a><\/em>\u00a0sobre su compa\u00f1ero.<\/p>\n\n\n\n<p>\u00abEs incre\u00edble, lo va a demostrar.\u00a0Solo las lesiones pueden impedirle seguir adelante.\u00a0Cuando ha estado en forma, ha demostrado que es importante, es una pena.\u00a0Lo necesitamos.\u00bb<\/p>\n\n\n\n<p>\u00abHazard es uno de los mejores del mundo, es incre\u00edble, y estoy seguro de que lo demostrar\u00e1 este a\u00f1o si las lesiones no lo previenen.\u00a0La temporada pasada ya demostr\u00f3 que era importante hasta que las lesiones lo detuvieron.\u00a0Eso demuestra por qu\u00e9 el Madrid pag\u00f3 tanto por \u00e9l.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.<\/p>\n","protected":false},"author":868,"featured_media":9792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[1529,78,4952,211],"enet_tags":{"player":["107417","31097"],"league":["87"],"team":["8633"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Modric explica como el &#039;incre\u00edble&#039; Hazard demostrar\u00e1 su val\u00eda en el Real Madrid<\/title>\n<meta name=\"description\" content=\"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modric explica como el &#039;incre\u00edble&#039; Hazard demostrar\u00e1 su val\u00eda en el Real Madrid\" \/>\n<meta property=\"og:description\" content=\"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T12:43:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T12:43:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg\",\"width\":1024,\"height\":683,\"caption\":\"MADRID, SPAIN - NOVEMBER 23: Eden Hazard of Real Madrid CF in action during the La Liga match between Real Madrid CF and Real Sociedad at Estadio Santiago Bernabeu on November 23, 2019 in Madrid, Spain. (Photo by Gonzalo Arroyo Moreno\/Getty Images)\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/\",\"name\":\"Modric explica como el 'incre\u00edble' Hazard demostrar\u00e1 su val\u00eda en el Real Madrid\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#primaryimage\"},\"datePublished\":\"2020-10-06T12:43:46+00:00\",\"dateModified\":\"2020-10-06T12:43:47+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modric explica como el &#8216;incre\u00edble&#8217; Hazard demostrar\u00e1 su val\u00eda en el Real Madrid\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modric explica como el 'incre\u00edble' Hazard demostrar\u00e1 su val\u00eda en el Real Madrid","description":"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Modric explica como el 'incre\u00edble' Hazard demostrar\u00e1 su val\u00eda en el Real Madrid","og_description":"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-10-06T12:43:46+00:00","article_modified_time":"2020-10-06T12:43:47+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg","width":1024,"height":683,"caption":"MADRID, SPAIN - NOVEMBER 23: Eden Hazard of Real Madrid CF in action during the La Liga match between Real Madrid CF and Real Sociedad at Estadio Santiago Bernabeu on November 23, 2019 in Madrid, Spain. (Photo by Gonzalo Arroyo Moreno\/Getty Images)"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/","name":"Modric explica como el 'incre\u00edble' Hazard demostrar\u00e1 su val\u00eda en el Real Madrid","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#primaryimage"},"datePublished":"2020-10-06T12:43:46+00:00","dateModified":"2020-10-06T12:43:47+00:00","author":{"@id":""},"description":"Luka Modric est\u00e1 seguro de que Eden Hazard demostrar\u00e1 que sus cr\u00edticos del Real Madrid est\u00e1n equivocados una vez que se libere de las lesiones que lo han frenado.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/modric-explica-como-el-increible-hazard-demostrara-su-valia-en-el-real-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Modric explica como el &#8216;incre\u00edble&#8217; Hazard demostrar\u00e1 su val\u00eda en el Real Madrid"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/10\/GettyImages-1189903235.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/9791"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/868"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=9791"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/9791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/9792"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=9791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=9791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=9791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}