{"id":7605,"date":"2020-08-25T22:01:00","date_gmt":"2020-08-25T22:01:00","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=7605"},"modified":"2020-08-25T22:01:04","modified_gmt":"2020-08-25T22:01:04","slug":"joachim-low-explica-la-ausencia-continua-de-muller-y-boateng","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/","title":{"rendered":"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng"},"content":{"rendered":"\n<h2>El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.\u00a0<\/h2>\n\n\n\n<p>Joachim L\u00f6w y Alemania otra vez excluyeron de la lista del equipo a Jerome Boateng y Thomas M\u00fcller para los partidos contra Suiza y Espa\u00f1a de la UEFA Nations League.&nbsp;<\/p>\n\n\n\n<p>Esta decisi\u00f3n de excluirlos llega como una sorpresa despu\u00e9s de haber terminado la temporada con el <em><a href=\"https:\/\/acefootball.com\/es\/partido\/paris-saint-germain\/3363670\/\" target=\"_blank\" rel=\"noreferrer noopener\">segundo triplete<\/a><\/em> de sus carreras a nivel de clubes. Pero L\u00f6w piensa que necesita reconstruir el equipo y concentrarse en los talentos m\u00e1s j\u00f3venes.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"de\" dir=\"ltr\">Unser Kader \ud83c\udde9\ud83c\uddea f\u00fcr die anstehenden Partien in der <a href=\"https:\/\/twitter.com\/hashtag\/NationsLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#NationsLeague<\/a>\u2757<br><br>\ud83c\udd9a <a href=\"https:\/\/twitter.com\/SeFutbol?ref_src=twsrc%5Etfw\">@sefutbol<\/a> \ud83c\uddea\ud83c\uddf8<br>\ud83c\udd9a <a href=\"https:\/\/twitter.com\/SFV_ASF?ref_src=twsrc%5Etfw\">@SFV_ASF<\/a>\u00a0\ud83c\udde8\ud83c\udded<a href=\"https:\/\/twitter.com\/hashtag\/DieMannschaft?src=hash&amp;ref_src=twsrc%5Etfw\">#DieMannschaft<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GERESP?src=hash&amp;ref_src=twsrc%5Etfw\">#GERESP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SUIGER?src=hash&amp;ref_src=twsrc%5Etfw\">#SUIGER<\/a> <a href=\"https:\/\/t.co\/y9WhNHmCaW\">pic.twitter.com\/y9WhNHmCaW<\/a><\/p>&mdash; Die Mannschaft (@DFB_Team) <a href=\"https:\/\/twitter.com\/DFB_Team\/status\/1298268158311063554?ref_src=twsrc%5Etfw\">August 25, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Tras el anuncio de la convocatoria de este martes, L\u00f6w coment\u00f3 que la edad es uno de los factores que influyen en su decisi\u00f3n de cortar jugadores para representar a Alemania. Toni Kroos es el m\u00e1s viejo de los que convoc\u00f3 con 30 a\u00f1os cumplidos.&nbsp;<\/p>\n\n\n\n<p>\u201cAmbos jugadores tuvieron muy buenas actuaciones y comprobaron lo valiosos que son para su equipo,\u201d cit\u00f3 <em><a href=\"https:\/\/www.goal.com\/en\/news\/low-muller-boateng-out-of-germany-squad\/1p4zpkxakpmy519v4ganiz58ut\" target=\"_blank\" rel=\"noreferrer noopener\">Goal<\/a><\/em> a L\u00f6w.\u00a0<\/p>\n\n\n\n<p>El estratega alem\u00e1n est\u00e1 en una misi\u00f3n de reconstruir el conjunto alem\u00e1n despu\u00e9s del fiasco del Mundial del 2018. Piensa que los jugadores j\u00f3venes son los que necesitan m\u00e1s tiempo para adaptarse y crear un futuro para el equipo.&nbsp;<\/p>\n\n\n\n<p>\u201cSin embargo, decidimos optar por otros jugadores despu\u00e9s del Mundial. Queremos que tengan espacio para desarrollarse. Estos j\u00f3venes talentos se han desarrollado muy bien y pudimos hacer los cambios bastante r\u00e1pido.&nbsp;<\/p>\n\n\n\n<p>\u201cSi la situaci\u00f3n fuera diferente, ser\u00eda el primero en reconsiderar mi decisi\u00f3n. Pero ahora mismo no veo raz\u00f3n alguna para hacerlo. Este camino es el correcto\u201d.&nbsp;<\/p>\n\n\n\n<p>Alemania enfrentar\u00e1 a Espa\u00f1a el 3 de Septiembre en Stuttgart antes de medirse a Suiza tres d\u00edas despu\u00e9s en el mismo estadio.<\/p>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-ace-football-espanol\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"MZnO55GM4I\"><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/neymar-y-mbappe-chocan-contra-la-aplanadora-del-bayern\/\">Neymar y Mbapp\u00e9 chocan contra la aplanadora del Bayern<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abNeymar y Mbapp\u00e9 chocan contra la aplanadora del Bayern\u00bb \u2014 Ace Football Espa\u00f1ol\" src=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/neymar-y-mbappe-chocan-contra-la-aplanadora-del-bayern\/embed\/#?secret=MZnO55GM4I\" data-secret=\"MZnO55GM4I\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng. <\/p>\n","protected":false},"author":258,"featured_media":-101101226216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[73],"tags":[4534,8280,6669,1259],"enet_tags":{"team":["8570"],"player":["78652","116772"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng<\/title>\n<meta name=\"description\" content=\"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng\" \/>\n<meta property=\"og:description\" content=\"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-25T22:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-25T22:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/08\/GettyImages-937405868.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/><meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/08\/GettyImages-937405868.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@IAmTomSpiegel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pavel I. Meda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/\",\"name\":\"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#primaryimage\"},\"datePublished\":\"2020-08-25T22:01:00+00:00\",\"dateModified\":\"2020-08-25T22:01:04+00:00\",\"author\":{\"@id\":\"https:\/\/acefootball.com\/es\/#\/schema\/person\/c817b858136f968b8b984c68fcf4aa84\"},\"description\":\"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/acefootball.com\/es\/#\/schema\/person\/c817b858136f968b8b984c68fcf4aa84\",\"name\":\"Pavel I. Meda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5d2d4f16693b918e4e93034452d5ee4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5d2d4f16693b918e4e93034452d5ee4c?s=96&d=mm&r=g\",\"caption\":\"Pavel I. Meda\"},\"description\":\"Football writer and journalist with 10 years of previous experience who loves his job and always likes to appreciate this beautiful sport. I've worked for companies such as Goal.com and Underdog Global Sports in the past. I am also an avid film and pop culture fan who spends his free time consuming any interesting story that is worth telling.\",\"sameAs\":[\"https:\/\/www.instagram.com\/rampantintellectual\/\",\"https:\/\/www.linkedin.com\/in\/pavel-ibarra-meda\",\"https:\/\/twitter.com\/IAmTomSpiegel\"],\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/tomasibarra\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng","description":"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/","og_locale":"es_ES","og_type":"article","og_title":"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng","og_description":"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-08-25T22:01:00+00:00","article_modified_time":"2020-08-25T22:01:04+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/08\/GettyImages-937405868.jpg","height":683,"width":1024},{"width":1200,"height":630,"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/08\/GettyImages-937405868.jpg","twitter_creator":"@IAmTomSpiegel","twitter_misc":{"Escrito por":"Pavel I. Meda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2020\/08\/937405868.jpg","width":1200,"height":630},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/","name":"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#primaryimage"},"datePublished":"2020-08-25T22:01:00+00:00","dateModified":"2020-08-25T22:01:04+00:00","author":{"@id":"https:\/\/acefootball.com\/es\/#\/schema\/person\/c817b858136f968b8b984c68fcf4aa84"},"description":"El entrenador de Alemania, Joachim L\u00f6w planea reconstruir el equipo con estrellas j\u00f3venes. Explica las ausencias de M\u00fcller y Boateng.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/joachim-low-explica-la-ausencia-continua-de-muller-y-boateng\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Joachim L\u00f6w explica la ausencia continua de M\u00fcller y Boateng"}]},{"@type":"Person","@id":"https:\/\/acefootball.com\/es\/#\/schema\/person\/c817b858136f968b8b984c68fcf4aa84","name":"Pavel I. Meda","image":{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/5d2d4f16693b918e4e93034452d5ee4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d2d4f16693b918e4e93034452d5ee4c?s=96&d=mm&r=g","caption":"Pavel I. Meda"},"description":"Football writer and journalist with 10 years of previous experience who loves his job and always likes to appreciate this beautiful sport. I've worked for companies such as Goal.com and Underdog Global Sports in the past. I am also an avid film and pop culture fan who spends his free time consuming any interesting story that is worth telling.","sameAs":["https:\/\/www.instagram.com\/rampantintellectual\/","https:\/\/www.linkedin.com\/in\/pavel-ibarra-meda","https:\/\/twitter.com\/IAmTomSpiegel"],"url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/tomasibarra\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/08\/GettyImages-937405868.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/7605"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/258"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=7605"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/7605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101226216"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=7605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=7605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=7605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}