{"id":15749,"date":"2021-06-09T23:15:06","date_gmt":"2021-06-09T21:15:06","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15749"},"modified":"2021-06-09T23:15:06","modified_gmt":"2021-06-09T21:15:06","slug":"no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/","title":{"rendered":"&#8216;No esperes m\u00e1s que grandeza&#8217; de Ronaldo en la Eurocopa 2020"},"content":{"rendered":"\n<h2 id=\"h-un-ronaldo-envejecido-sigue-siendo-una-de-las-lites-del-f-tbol-y-un-compa-ero-suyo-advierte-a-los-rivales-de-portugal-que-tengan-cuidado-con-su-capit-n\">Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero suyo advierte a los rivales de Portugal que tengan cuidado con su capit\u00e1n.<\/h2>\n\n\n\n<p>Cristiano Ronaldo se est\u00e1 \u00abpreparando de la mejor manera\u00bb para la Eurocopa 2020, seg\u00fan Jos\u00e9 Fonte, que no espera \u00abm\u00e1s que grandeza\u00bb del capit\u00e1n de Portugal en el torneo de este verano.<\/p>\n\n\n\n<p>Despu\u00e9s de marcar 29 goles en 33 partidos con su club para ganar su primera Capocannoniere, el cinco veces ganador del Bal\u00f3n de Oro se prepara para ayudar a su selecci\u00f3n a defender su corona continental.<\/p>\n\n\n\n<p>A pesar de haber superado la treintena, el ex jugador del Real Madrid ser\u00e1 uno de los<em><a href=\"https:\/\/acefootball.com\/football-news\/top-5-players-to-watch-during-the-uefa-euro-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"> jugadores m\u00e1s interesantes<\/a><\/em> de la Eurocopa.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Cristiano Ronaldo records at the Euro\u2019s<br><br>&#8211; joint top scorer with 9 goals<br>&#8211; only player to score at 4 Euro\u2019s<br>&#8211; played most games and scored most goals in qualifiers<br><br>\ud83c\uddf5\ud83c\uddf9 <a href=\"https:\/\/twitter.com\/hashtag\/CR7?src=hash&amp;ref_src=twsrc%5Etfw\">#CR7<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RecordBreaker?src=hash&amp;ref_src=twsrc%5Etfw\">#RecordBreaker<\/a><\/p>&mdash; Outside The Box (@OutSide_TheBox2) <a href=\"https:\/\/twitter.com\/OutSide_TheBox2\/status\/1401072015805714433?ref_src=twsrc%5Etfw\">June 5, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>\u00abEs nuestro l\u00edder, nuestro capit\u00e1n\u00bb, dijo Fonte sobre Ronaldo, en declaraciones a Jim White y Simon Jordan en\u00a0<em><a href=\"https:\/\/talksport.com\/topic\/jim-white-talksport\/\" target=\"_blank\" rel=\"noreferrer noopener\">talkSPORT<\/a><\/em>.<\/p>\n\n\n\n<p>\u00abComo siempre se est\u00e1 preparando de la mejor manera. Es uno de los mejores profesionales. Los n\u00fameros hablan por s\u00ed solos\u00bb.<\/p>\n\n\n\n<p>\u00abSigue en marcha, sigue siendo una bestia, as\u00ed que no esperen otra cosa que grandeza\u00bb.<\/p>\n\n\n\n<p>Portugal comenzar\u00e1 la defensa de su t\u00edtulo enfrent\u00e1ndose a Hungr\u00eda el pr\u00f3ximo martes. A continuaci\u00f3n, se enfrentar\u00e1 a Alemania el 19 de junio, y cinco d\u00edas m\u00e1s tarde a Francia, en las jornadas 2 y 3, respectivamente, del Grupo F del \u00abgrupo de la muerte\u00bb.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero suyo advierte a los rivales de Portugal que tengan cuidado con su capit\u00e1n. Cristiano Ronaldo se est\u00e1 \u00abpreparando de la mejor manera\u00bb para la Eurocopa 2020, seg\u00fan Jos\u00e9 Fonte, que no espera \u00abm\u00e1s que grandeza\u00bb del capit\u00e1n de Portugal en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":-101101267958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[259,3055,1129],"enet_tags":{"player":["30893"],"league":["50"],"team":["8361"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&#039;No esperes m\u00e1s que grandeza&#039; de Ronaldo en la Eurocopa 2020<\/title>\n<meta name=\"description\" content=\"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;No esperes m\u00e1s que grandeza&#039; de Ronaldo en la Eurocopa 2020\" \/>\n<meta property=\"og:description\" content=\"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T21:15:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/06\/1321770082-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1262\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/06\/1321770082-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Team Acefootball\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/\",\"name\":\"'No esperes m\u00e1s que grandeza' de Ronaldo en la Eurocopa 2020\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#primaryimage\"},\"datePublished\":\"2021-06-09T21:15:06+00:00\",\"dateModified\":\"2021-06-09T21:15:06+00:00\",\"author\":{\"@id\":\"https:\/\/acefootball.com\/es\/#\/schema\/person\/9b4be16c64ad64ec1ef43b3fec19abcf\"},\"description\":\"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;No esperes m\u00e1s que grandeza&#8217; de Ronaldo en la Eurocopa 2020\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/acefootball.com\/es\/#\/schema\/person\/9b4be16c64ad64ec1ef43b3fec19abcf\",\"name\":\"Team Acefootball\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/19d749670aa1f01ecf6bba95169ecaf2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/19d749670aa1f01ecf6bba95169ecaf2?s=96&d=mm&r=g\",\"caption\":\"Team Acefootball\"},\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/solrek\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'No esperes m\u00e1s que grandeza' de Ronaldo en la Eurocopa 2020","description":"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/","og_locale":"es_ES","og_type":"article","og_title":"'No esperes m\u00e1s que grandeza' de Ronaldo en la Eurocopa 2020","og_description":"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-06-09T21:15:06+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/06\/1321770082-1.jpg","height":1262,"width":1920}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/06\/1321770082-1.jpg","twitter_misc":{"Escrito por":"Team Acefootball","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/","name":"'No esperes m\u00e1s que grandeza' de Ronaldo en la Eurocopa 2020","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#primaryimage"},"datePublished":"2021-06-09T21:15:06+00:00","dateModified":"2021-06-09T21:15:06+00:00","author":{"@id":"https:\/\/acefootball.com\/es\/#\/schema\/person\/9b4be16c64ad64ec1ef43b3fec19abcf"},"description":"Un Ronaldo envejecido sigue siendo una de las \u00e9lites del f\u00fatbol, y un compa\u00f1ero advierte a los rivales de Portugal que tengan cuidado.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/no-esperes-mas-que-grandeza-de-ronaldo-en-la-eurocopa-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"&#8216;No esperes m\u00e1s que grandeza&#8217; de Ronaldo en la Eurocopa 2020"}]},{"@type":"Person","@id":"https:\/\/acefootball.com\/es\/#\/schema\/person\/9b4be16c64ad64ec1ef43b3fec19abcf","name":"Team Acefootball","image":{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/19d749670aa1f01ecf6bba95169ecaf2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19d749670aa1f01ecf6bba95169ecaf2?s=96&d=mm&r=g","caption":"Team Acefootball"},"url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/solrek\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/06\/1321770082-1.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15749"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15749"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101267958"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}