{"id":15586,"date":"2021-05-14T23:17:16","date_gmt":"2021-05-14T21:17:16","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15586"},"modified":"2021-05-14T23:17:25","modified_gmt":"2021-05-14T21:17:25","slug":"luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/","title":{"rendered":"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020"},"content":{"rendered":"\n<h2 id=\"h-de-cara-a-la-eurocopa-2020-luis-enrique-habl-sobre-las-posibilidades-reales-de-espa-a-de-ganar-el-torneo-durante-el-verano\">De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.<\/h2>\n\n\n\n<p>Reconozc\u00e1moslo, la Selecci\u00f3n de Espa\u00f1a de Luis Enrique est\u00e1 muy lejos de la plantilla que marc\u00f3 una \u00e9poca en el f\u00fatbol entre 2008 y 2012. En ese periodo, ganaron dos Eurocopas y la Copa Mundial de la FIFA 2010. Lo hicieron con la que posiblemente sea la generaci\u00f3n de futbolistas m\u00e1s talentosa jam\u00e1s reunida por su pa\u00eds. A d\u00eda de hoy, el equipo dirigido por Luis Enrique no se acerca ni de lejos a aquel equipo legendario.<\/p>\n\n\n\n<p>Sin embargo, el t\u00e9cnico espa\u00f1ol est\u00e1 convencido de que tienen lo necesario para competir en el torneo el pr\u00f3ximo verano. De hecho, el <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/enrique-sobre-la-dificultad-de-derribar-a-sus-rivales\/\">t\u00e9cnico <\/a><\/em>cree que este equipo tiene posibilidades de ganar el t\u00edtulo. Para ello, tendr\u00e1 que superar la fase de grupos contra selecciones como Eslovaquia, Suecia y Polonia. Las cuatro selecciones forman parte del Grupo E del torneo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83c\udfc6 FALTA UN MES PARA EL DEBUT DE LA <a href=\"https:\/\/twitter.com\/SeFutbol?ref_src=twsrc%5Etfw\">@SEFUTBOL<\/a> EN LA EUROCOPA<br><br>\ud83d\udcaa\ud83c\udffc As\u00ed analiza <a href=\"https:\/\/twitter.com\/LUISENRIQUE21?ref_src=twsrc%5Etfw\">@LUISENRIQUE21<\/a> a los rivales<br><br>\ud83d\udde3\ufe0f &quot;Somos favoritos en el grupo, pero tenemos que confirmarlo con resultados&quot;<a href=\"https:\/\/twitter.com\/hashtag\/SomosEspa%C3%B1a?src=hash&amp;ref_src=twsrc%5Etfw\">#SomosEspa\u00f1a<\/a><a href=\"https:\/\/twitter.com\/hashtag\/SomosFederaci%C3%B3n?src=hash&amp;ref_src=twsrc%5Etfw\">#SomosFederaci\u00f3n<\/a> <a href=\"https:\/\/t.co\/MBFsFvNsD6\">pic.twitter.com\/MBFsFvNsD6<\/a><\/p>&mdash; Selecci\u00f3n Espa\u00f1ola de F\u00fatbol (@SeFutbol) <a href=\"https:\/\/twitter.com\/SeFutbol\/status\/1393152583141838850?ref_src=twsrc%5Etfw\">May 14, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 id=\"h-luis-enrique-tiene-muchas-esperanzas-puestas-en-espa-a\">Luis Enrique tiene muchas esperanzas puestas en Espa\u00f1a.<\/h3>\n\n\n\n<p>El d\u00eda que se present\u00f3 la lista de convocados, esto es lo que recogi\u00f3\u00a0<em><a href=\"https:\/\/www.marca.com\/futbol\/eurocopa\/2021\/05\/14\/609eb43ce2704e3b4b8b45c8.html\" target=\"_blank\" rel=\"noreferrer noopener\">Marca<\/a><\/em>\u00a0de Luis Enrique: \u201cSeguimos siendo una marca potente en el mundo del f\u00fatbol. Ahora, \u00bfqu\u00e9 estamos intentando hacer? Recuperar y poder imitar a esos que en su momento fueron \u00fanicos y consiguieron algo que nunca hab\u00edamos conseguido desde una posici\u00f3n en la que son conscientes los jugadores que podemos ser campeones, claro que s\u00ed.<\/p>\n\n\n\n<p>\u201cSi estamos al nivel que se nos supone\u00a0y e incluso lo podemos superar y seguimos repitiendo las cosas que sabemos, pero el nivel de confianza genera una l\u00ednea ascendente de rendimiento, podemos optar a todo. No hay ninguna duda. No me da miedo afrontar ese reto, pero hay que valorar luego en la justa medida lo que estamos intentando hacer, qu\u00e9 perfil de jugadores tenemos, una selecci\u00f3n joven que quiere crecer, que tiene hambre, que juega bien al f\u00fatbol, que defiende bien\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano. Reconozc\u00e1moslo, la Selecci\u00f3n de Espa\u00f1a de Luis Enrique est\u00e1 muy lejos de la plantilla que marc\u00f3 una \u00e9poca en el f\u00fatbol entre 2008 y 2012. En ese periodo, ganaron dos Eurocopas y la [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101266367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[73],"tags":[5774,3055,203],"enet_tags":{"team":["6720"],"league":["50"],"player":["269030"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020<\/title>\n<meta name=\"description\" content=\"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020\" \/>\n<meta property=\"og:description\" content=\"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T21:17:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-14T21:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1309604340.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1309604340.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/\",\"name\":\"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#primaryimage\"},\"datePublished\":\"2021-05-14T21:17:16+00:00\",\"dateModified\":\"2021-05-14T21:17:25+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020","description":"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/","og_locale":"es_ES","og_type":"article","og_title":"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020","og_description":"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-05-14T21:17:16+00:00","article_modified_time":"2021-05-14T21:17:25+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1309604340.jpg","height":683,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1309604340.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/","name":"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#primaryimage"},"datePublished":"2021-05-14T21:17:16+00:00","dateModified":"2021-05-14T21:17:25+00:00","author":{"@id":""},"description":"De cara a la Eurocopa 2020, Luis Enrique habl\u00f3 sobre las posibilidades reales de Espa\u00f1a de ganar el torneo durante el verano.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/luis-enrique-habla-de-la-esperanza-de-espana-en-la-eurocopa-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Luis Enrique habla de la esperanza de Espa\u00f1a en la Eurocopa 2020"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1309604340.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15586"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15586"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101266367"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}