{"id":15524,"date":"2021-05-07T22:13:26","date_gmt":"2021-05-07T20:13:26","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15524"},"modified":"2021-05-07T22:13:32","modified_gmt":"2021-05-07T20:13:32","slug":"informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/","title":{"rendered":"Informe: El Reino Unido planea trasladar la final de la Champions League"},"content":{"rendered":"\n<h2 id=\"h-tras-muchas-consideraciones-por-parte-del-gobierno-del-reino-unido-han-puesto-en-marcha-un-plan-para-reubicar-la-final-de-la-uefa-champions-league\">Tras muchas consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.<\/h2>\n\n\n\n<p>Como comentamos <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hinchas-del-chelsea-y-del-city-quieren-la-final-de-la-ucl-en-inglaterra\/\">ayer<\/a><\/em>, el Gobierno del Reino Unido acaba de involucrarse en los planes para reubicar la final de la UEFA Champions League. La idea es presionar a la UEFA para que se celebre en suelo ingl\u00e9s, ya que ambos finalistas pertenecen a la Premier League. Lo que inici\u00f3 este plan es la decisi\u00f3n que tom\u00f3 el Gobierno de colocar a Turqu\u00eda dentro de su lista roja. Se trata de naciones que no pueden tener ning\u00fan tipo de relaci\u00f3n con el Reino Unido debido a la pandemia mundial.<\/p>\n\n\n\n<p>A diferencia de otros lugares, Turqu\u00eda a\u00fan no ha puesto en orden sus asuntos con la crisis. Los casos siguen aumentando y los viajes est\u00e1n ampliamente restringidos all\u00ed al menos durante el resto de 2021. El Gobierno del Reino Unido, encabezado por el Secretario de Transporte, tom\u00f3 esta decisi\u00f3n con los 8.000 hinchas a los que se les permiti\u00f3 asistir a la final. A pesar de que la UEFA sigue presionando para que la final se celebre en Turqu\u00eda, el Reino Unido se mantiene muy firme en esta decisi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud83d\udea8 BREAKING\ud83d\udea8<br><br>Transport Secretary Grant Shapps announces that Turkey has been added to the UK&#39;s red list ahead of the Champions League final between Chelsea &amp; Manchester City on May 29th in Istanbul <br><br>The FA are now in talks with UEFA about it being moved to the UK <a href=\"https:\/\/t.co\/BnYBHTrSZY\">pic.twitter.com\/BnYBHTrSZY<\/a><\/p>&mdash; Football Daily (@footballdaily) <a href=\"https:\/\/twitter.com\/footballdaily\/status\/1390708677049556994?ref_src=twsrc%5Etfw\">May 7, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 id=\"h-grant-shapps-est-abierto-a-que-inglaterra-sea-sede\">Grant Shapps est\u00e1 abierto a que Inglaterra sea sede.<\/h3>\n\n\n\n<p>Durante su \u00faltima reuni\u00f3n informativa, Grant Shapps explic\u00f3 que el Reino Unido est\u00e1 abierto a proponer sedes dentro del pa\u00eds para la final de la Champions League. No considera que la UEFA deba oponerse a ello porque los dos clubes que llegaron a la final son de Inglaterra. Esto es lo que recogi\u00f3<em><a href=\"https:\/\/www.skysports.com\/football\/news\/11945\/12299723\/champions-league-uefa-considering-options-for-istanbul-final-after-uk-add-turkey-to-travel-red-list\" target=\"_blank\" rel=\"noreferrer noopener\">Sky Sports<\/a><\/em>\u00a0de la rueda de prensa de Shapp: \u00abMe temo que tenemos que poner a Turqu\u00eda en la lista roja. Esto tendr\u00e1 varias ramificaciones. En primer lugar, significa que con respecto a la Champions League, los aficionados no deben viajar a Turqu\u00eda\u00bb.<\/p>\n\n\n\n<p>\u00abLa FA est\u00e1 en conversaciones con la UEFA sobre este tema. Estamos muy abiertos a acoger la final, pero en \u00faltima instancia es una decisi\u00f3n de la UEFA. Por supuesto, el Reino Unido ya tiene un historial de \u00e9xito en cuanto a partidos de f\u00fatbol con espectadores, as\u00ed que estamos bien situados para hacerlo. Estamos muy abiertos a ello, pero al final es una decisi\u00f3n que tiene que tomar la UEFA, pero teniendo en cuenta que hay dos clubes ingleses en esa final. Estamos a la espera de lo que tengan que decir\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras muchas consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League. Como comentamos ayer, el Gobierno del Reino Unido acaba de involucrarse en los planes para reubicar la final de la UEFA Champions League. La idea es presionar a la UEFA [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101265677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[67],"tags":[82,1365,888],"enet_tags":{"league":["42"],"team":["8455","8456"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Informe: El Reino Unido planea trasladar la final de la Champions League<\/title>\n<meta name=\"description\" content=\"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informe: El Reino Unido planea trasladar la final de la Champions League\" \/>\n<meta property=\"og:description\" content=\"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T20:13:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T20:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1268049525.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1268049525.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/\",\"name\":\"Informe: El Reino Unido planea trasladar la final de la Champions League\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#primaryimage\"},\"datePublished\":\"2021-05-07T20:13:26+00:00\",\"dateModified\":\"2021-05-07T20:13:32+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informe: El Reino Unido planea trasladar la final de la Champions League\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informe: El Reino Unido planea trasladar la final de la Champions League","description":"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/","og_locale":"es_ES","og_type":"article","og_title":"Informe: El Reino Unido planea trasladar la final de la Champions League","og_description":"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-05-07T20:13:26+00:00","article_modified_time":"2021-05-07T20:13:32+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1268049525.jpg","height":687,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1268049525.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/","name":"Informe: El Reino Unido planea trasladar la final de la Champions League","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#primaryimage"},"datePublished":"2021-05-07T20:13:26+00:00","dateModified":"2021-05-07T20:13:32+00:00","author":{"@id":""},"description":"Tras consideraciones por parte del Gobierno del Reino Unido, han puesto en marcha un plan para reubicar la final de la UEFA Champions League.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/informe-el-reino-unido-planea-trasladar-la-final-de-la-champions-league\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Informe: El Reino Unido planea trasladar la final de la Champions League"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1268049525.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15524"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15524"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101265677"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}