{"id":15467,"date":"2021-05-03T18:14:13","date_gmt":"2021-05-03T16:14:13","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15467"},"modified":"2021-05-03T18:14:18","modified_gmt":"2021-05-03T16:14:18","slug":"mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/","title":{"rendered":"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma"},"content":{"rendered":"\n<h2 id=\"h-edouard-mendy-cree-que-el-chelsea-ver-definitivamente-lo-mejor-de-timo-werner-y-kai-havertz-a-partir-de-la-pr-xima-temporada\">Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \u00ablo mejor\u00bb de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.<\/h2>\n\n\n\n<p>Es solo cuesti\u00f3n de tiempo que Werner y Havertz alcancen un nivel prol\u00edfico en el Chelsea, afirma su compa\u00f1ero de equipo en los Blues, Edouard Mendy.<\/p>\n\n\n\n<p>Se esperaba mucho de las dos grandes incorporaciones cuando llegaron al oeste de Londres desde el RB Leipzig y el Bayer Leverkusen durante el verano de 2020, pero ninguno de los dos ha estado a la altura de su precio en la Premier League.<\/p>\n\n\n\n<p>Ha habido destellos de brillantez y alg\u00fan que otro motivo de optimismo, pero es posible que la regularidad resulte esquiva hasta 2021-22.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">How Chelsea\u2019s signings have done this season.. <br><br>23 clean sheets for Mendy this season<br><br>46 G\/A for Werner, Havertz &amp; Ziyech this season <br><br>13 clean sheets for Silva this season <br><br>10 G\/A for Ben Chilwell this season<br><br>Not too bad at all..<\/p>&mdash; Conn (@ConnCFC) <a href=\"https:\/\/twitter.com\/ConnCFC\/status\/1388560207526174725?ref_src=twsrc%5Etfw\">May 1, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>El portero del Chelsea, Mendy, dijo a la\u00a0<em><a href=\"https:\/\/www.chelseafc.com\/es\/news\/2021\/05\/03\/mendy--veremos-lo-mejor-de-timo-y-kai?cardIndex=0-0\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00e1gina web<\/a><\/em> oficial del club: \u201cSon muy buenos jugadores. Son j\u00f3venes y es la primera vez que se trasladan a otro pa\u00eds.<\/p>\n\n\n\n<p>\u201cCreo que han necesitado un par de meses para adaptarse y entender la Premier League, pero los veo todos los d\u00edas y s\u00e9 lo buenos que son. Me alegro por ellos. Han demostrado sus cualidades en el campo.<\/p>\n\n\n\n<p>\u00abLa pr\u00f3xima temporada, al 100%, veremos lo mejor de Timo y Kai. Incluso este a\u00f1o hemos disfrutado de su buen nivel de rendimiento y son importantes para nosotros\u00bb.<\/p>\n\n\n\n<p>Havertz, que ha sido utilizado como falso nueve por Thomas Tuchel en las \u00faltimas semanas, anot\u00f3 un doblete en la victoria del Chelsea sobre su rival, el Fulham, por 2-0 en su \u00faltimo encuentro de la Premier League.<\/p>\n\n\n\n<p>Werner fue el autor de uno de esos goles y es uno de los cinco jugadores de la liga inglesa que ha alcanzado las dos cifras de goles y asistencias esta temporada.<\/p>\n\n\n\n<p>El jugador de 24 a\u00f1os ha anotado 11 goles, mientras que Havertz lleva ocho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \u00ablo mejor\u00bb de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada. Es solo cuesti\u00f3n de tiempo que Werner y Havertz alcancen un nivel prol\u00edfico en el Chelsea, afirma su compa\u00f1ero de equipo en los Blues, Edouard Mendy. Se esperaba mucho de las dos grandes [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101265266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[1365,8322,1605,1390],"enet_tags":{"team":["8455"],"player":["749736","450980"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma<\/title>\n<meta name=\"description\" content=\"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente &quot;lo mejor&quot; de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma\" \/>\n<meta property=\"og:description\" content=\"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente &quot;lo mejor&quot; de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T16:14:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-03T16:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1299599811.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1299599811.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/\",\"name\":\"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#primaryimage\"},\"datePublished\":\"2021-05-03T16:14:13+00:00\",\"dateModified\":\"2021-05-03T16:14:18+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \\\"lo mejor\\\" de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma","description":"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \"lo mejor\" de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/","og_locale":"es_ES","og_type":"article","og_title":"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma","og_description":"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \"lo mejor\" de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-05-03T16:14:13+00:00","article_modified_time":"2021-05-03T16:14:18+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1299599811.jpg","height":679,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1299599811.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/","name":"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#primaryimage"},"datePublished":"2021-05-03T16:14:13+00:00","dateModified":"2021-05-03T16:14:18+00:00","author":{"@id":""},"description":"Edouard Mendy cree que el Chelsea ver\u00e1 definitivamente \"lo mejor\" de Timo Werner y Kai Havertz a partir de la pr\u00f3xima temporada.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mendy-confia-en-que-havertz-y-werner-alcancen-su-mejor-forma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mendy conf\u00eda en que Havertz y Werner alcancen su mejor forma"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/05\/GettyImages-1299599811.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15467"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15467"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101265266"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}