{"id":15353,"date":"2021-04-19T22:57:40","date_gmt":"2021-04-19T20:57:40","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15353"},"modified":"2021-04-19T22:57:41","modified_gmt":"2021-04-19T20:57:41","slug":"iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/","title":{"rendered":"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester"},"content":{"rendered":"\n<h2 id=\"h-kelechi-iheanacho-est-en-el-mejor-momento-de-su-vida-y-est-encantado-de-haber-llevado-al-leicester-city-a-la-final-de-la-fa-cup\">Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.<\/h2>\n\n\n\n<p>Kelechi Iheanacho ha descrito la clasificaci\u00f3n del Leicester City para la final de la\u00a0<em><a href=\"https:\/\/acefootball.com\/es\/fa-cup\/\">FA Cup<\/a><\/em>\u00a0como un \u00absue\u00f1o hecho realidad\u00bb.<\/p>\n\n\n\n<p>Los Foxes silenciaron al Southampton (1-0) en el estadio de Wembley para llegar a la final de la competici\u00f3n por primera vez en 52 a\u00f1os.<\/p>\n\n\n\n<p>Sin embargo, les espera una dura tarea, ya que se enfrentar\u00e1n al Chelsea de Thomas Tuchel en su intento de levantar el prestigioso trofeo.<\/p>\n\n\n\n<p>En declaraciones a<em><a href=\"https:\/\/www.lcfc.com\/news\/2110586\/iheanacho-a-beautiful-wonderful-goal\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0LCFC TV<\/a><\/em>, el internacional nigeriano afirma estar en las nubes tras la hist\u00f3rica haza\u00f1a de su equipo.<\/p>\n\n\n\n<p>Aunque es consciente del duro trabajo que tienen por delante si quieren vencer a los Blues en el t\u00edtulo el 15 de mayo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud83d\udea8 EXTRA-TIME ON LCFC RADIO \ud83d\udea8<br><br>\ud83c\udf99 Dan Bates<br>\ud83e\udd8a Matt Elliott<br>\ud83e\udd8a Iwan Roberts<br><br>Join us as we look back on yesterday\u2019s FA Cup Semi-Final victory at Wembley \u2935\ufe0f <a href=\"https:\/\/t.co\/A5aFNUEE3U\">https:\/\/t.co\/A5aFNUEE3U<\/a><\/p>&mdash; Leicester City (@LCFC) <a href=\"https:\/\/twitter.com\/LCFC\/status\/1384191271451828225?ref_src=twsrc%5Etfw\">April 19, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>\u00abEs realmente incre\u00edble, es un sue\u00f1o hecho realidad\u00bb, dijo Iheanacho.<\/p>\n\n\n\n<p>\u00abNo sab\u00eda que iba a llegar as\u00ed, pero ahora estamos en la final, as\u00ed que estamos muy contentos\u00bb.<\/p>\n\n\n\n<p>\u00abTenemos que volver a trabajar duro y concentrarnos en nuestro pr\u00f3ximo partido. Esperemos que en la final trabajemos duro para ganar\u00bb.<\/p>\n\n\n\n<p>\u00abFue una buena sensaci\u00f3n verlos de nuevo en el estadio. Cuando jugamos, se les oye gritar y chillar\u00bb.<\/p>\n\n\n\n<p>Iheanacho describi\u00f3 su gol como \u00abhermoso\u00bb, al tiempo que reserv\u00f3 un elogio para su compa\u00f1ero de ataque, Jamie Vardy.<\/p>\n\n\n\n<p>\u00abEs un gol hermoso\u00bb, continu\u00f3. \u00abComo he dicho antes, la asociaci\u00f3n entre Vardy y yo es excepcional. Su forma de correr con el bal\u00f3n es realmente buena\u00bb.<\/p>\n\n\n\n<p>\u00abSe llev\u00f3 a los defensores y la recort\u00f3. Tuve mala suerte con el primer disparo. Rebot\u00f3 en el defensor y volvi\u00f3 a m\u00ed, y yo eleg\u00ed el c\u00f3rner. Estoy muy contento de que lo hayamos hecho juntos como equipo\u00bb.<\/p>\n\n\n\n<p>El Leicester City sigue buscando un puesto en la Champions League cuando reciba el jueves al West Bromwich Albion en el King Power Stadium.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup. Kelechi Iheanacho ha descrito la clasificaci\u00f3n del Leicester City para la final de la\u00a0FA Cup\u00a0como un \u00absue\u00f1o hecho realidad\u00bb. Los Foxes silenciaron al Southampton (1-0) en el estadio de [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101263770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[2199,8420,1155],"enet_tags":{"league":["132"],"player":["643709"],"team":["8197"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester<\/title>\n<meta name=\"description\" content=\"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester\" \/>\n<meta property=\"og:description\" content=\"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T20:57:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T20:57:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1300179198.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1300179198.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/\",\"name\":\"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#primaryimage\"},\"datePublished\":\"2021-04-19T20:57:40+00:00\",\"dateModified\":\"2021-04-19T20:57:41+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester","description":"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/","og_locale":"es_ES","og_type":"article","og_title":"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester","og_description":"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-04-19T20:57:40+00:00","article_modified_time":"2021-04-19T20:57:41+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1300179198.jpg","height":663,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1300179198.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/","name":"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#primaryimage"},"datePublished":"2021-04-19T20:57:40+00:00","dateModified":"2021-04-19T20:57:41+00:00","author":{"@id":""},"description":"Kelechi Iheanacho est\u00e1 en el mejor momento de su vida y est\u00e1 encantado de haber llevado al Leicester City a la final de la FA Cup.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/iheanacho-orgulloso-de-llegar-a-la-final-de-la-fa-cup-con-el-leicester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Iheanacho, orgulloso de llegar a la final de la FA Cup con el Leicester"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1300179198.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15353"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15353"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101263770"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}