{"id":15330,"date":"2021-04-16T18:37:49","date_gmt":"2021-04-16T16:37:49","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15330"},"modified":"2021-04-16T18:37:57","modified_gmt":"2021-04-16T16:37:57","slug":"tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/","title":{"rendered":"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo"},"content":{"rendered":"\n<h2 id=\"h-antes-de-la-semifinal-de-la-fa-cup-thomas-tuchel-lanz-un-desaf-o-al-t-tulo-al-manchester-city-de-pep-guardiola-para-la-pr-xima-temporada\">Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.<\/h2>\n\n\n\n<p>Thomas Tuchel no solo conf\u00eda en que su Chelsea pueda eliminar ma\u00f1ana al Manchester City de Guardiola en la semifinal de la FA Cup. Tambi\u00e9n cree que la pr\u00f3xima temporada ser\u00e1 muy diferente en cuanto a clubes competitivos que luchar\u00e1n por ganar la Premier League. De hecho, el t\u00e9cnico alem\u00e1n est\u00e1 convencido de que los Blues ser\u00e1n definitivamente un aspirante al t\u00edtulo en la pr\u00f3xima temporada.<\/p>\n\n\n\n<p>Aunque sus jugadores tienen que pensar primero en el d\u00eda de ma\u00f1ana, Tuchel est\u00e1 muy ilusionado con los resultados que puedan obtener el a\u00f1o que viene. Hay que tener en cuenta que el Chelsea y el Manchester City son los dos \u00fanicos clubes ingleses que han llegado a las <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/guardiola-felicita-a-su-equipo-tras-clasificarse-para-la-semifinal\/\">semifinales <\/a><\/em>de la Champions League. Esto bien podr\u00eda ser un preludio de una posible final, lo que a\u00f1ade un poco m\u00e1s de picante al partido de ma\u00f1ana. Por un lado, los Citizens buscan mantener vivo su sue\u00f1o de cu\u00e1druplete. Por el otro, los equipos de Tuchel quieren sorprender a todo el mundo con su intento de conseguir dos t\u00edtulos esta temporada.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;When he was coach in Barcelona&#8230;I was watching almost every game&quot;<br><br>Thomas Tuchel explains the influence Pep Guardiola had on his career as a manager ahead of Chelsea&#39;s <a href=\"https:\/\/twitter.com\/hashtag\/FACup?src=hash&amp;ref_src=twsrc%5Etfw\">#FACup<\/a> tie with Man City <a href=\"https:\/\/t.co\/b9xtbPGlC1\">pic.twitter.com\/b9xtbPGlC1<\/a><\/p>&mdash; The Sun Football \u26bd (@TheSunFootball) <a href=\"https:\/\/twitter.com\/TheSunFootball\/status\/1383089551254560776?ref_src=twsrc%5Etfw\">April 16, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 id=\"h-tuchel-est-ansioso-por-enfrentarse-a-pep-guardiola\">Tuchel est\u00e1 ansioso por enfrentarse a Pep Guardiola.<\/h3>\n\n\n\n<p>Debido a su pasado en la Bundesliga, Thomas Tuchel ya compiti\u00f3 con Pep Guardiola en el pasado. Seg\u00fan\u00a0<em><a href=\"https:\/\/www.bbc.com\/sport\/football\/56776703\" target=\"_blank\" rel=\"noreferrer noopener\">BBC Sport<\/a><\/em>, esto es lo que dijo el entrenador del Chelsea: \u00abTenemos que aceptar que hay una brecha entre nosotros y el Manchester City. Si miramos el calendario de la Premier League y los partidos de los \u00faltimos a\u00f1os, tenemos que aceptarlo. Y es importante que lo aceptemos sin hacernos demasiado peque\u00f1os. Desde el primer d\u00eda de la pr\u00f3xima temporada, les daremos caza. Intentaremos cerrar la brecha entre nosotros.<\/p>\n\n\n\n<p>\u00abTenemos que admitir que hay una brecha, pero durante 90 minutos somos muy conscientes y estamos muy seguros de que podemos cerrar la brecha ma\u00f1ana durante un partido. Cuando era entrenador del Barcelona no tuve la oportunidad de conocerlo personalmente, pero ve\u00eda casi todos los partidos. Me impresion\u00f3 mucho su forma de conseguir el \u00e9xito, el estilo de juego, todos los chicos de la academia, la posesi\u00f3n ofensiva del bal\u00f3n\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada. Thomas Tuchel no solo conf\u00eda en que su Chelsea pueda eliminar ma\u00f1ana al Manchester City de Guardiola en la semifinal de la FA Cup. Tambi\u00e9n cree que la pr\u00f3xima temporada [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101263465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[73],"tags":[1365,2199,888,2463,2919],"enet_tags":{"team":["8455","8456"],"league":["132"],"player":["150249","179347"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo<\/title>\n<meta name=\"description\" content=\"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo\" \/>\n<meta property=\"og:description\" content=\"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T16:37:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-16T16:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-533036106.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-533036106.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/\",\"name\":\"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#primaryimage\"},\"datePublished\":\"2021-04-16T16:37:49+00:00\",\"dateModified\":\"2021-04-16T16:37:57+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo","description":"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/","og_locale":"es_ES","og_type":"article","og_title":"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo","og_description":"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-04-16T16:37:49+00:00","article_modified_time":"2021-04-16T16:37:57+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-533036106.jpg","height":609,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-533036106.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/","name":"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#primaryimage"},"datePublished":"2021-04-16T16:37:49+00:00","dateModified":"2021-04-16T16:37:57+00:00","author":{"@id":""},"description":"Antes de la semifinal de la FA Cup, Thomas Tuchel lanz\u00f3 un desaf\u00edo al t\u00edtulo al Manchester City de Pep Guardiola para la pr\u00f3xima temporada.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/tuchel-desafia-al-manchester-city-de-guardiola-por-el-titulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tuchel desaf\u00eda al Manchester City de Guardiola por el t\u00edtulo"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-533036106.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15330"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15330"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101263465"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}