{"id":15325,"date":"2021-04-16T14:25:54","date_gmt":"2021-04-16T12:25:54","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15325"},"modified":"2021-04-16T14:25:54","modified_gmt":"2021-04-16T12:25:54","slug":"firmino-sobre-su-forma-en-el-liverpool-esta-temporada","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/","title":{"rendered":"Firmino sobre su forma en el Liverpool esta temporada"},"content":{"rendered":"\n<h2 id=\"h-el-delantero-de-los-reds-admite-que-ha-tenido-problemas-esta-temporada-pero-est-decidido-a-recuperar-su-chispa\">El delantero de los <em>Reds<\/em> admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.<\/h2>\n\n\n\n<p>Roberto Firmino admite que ha soportado una \u00abtemporada dif\u00edcil\u00bb en el Liverpool, con el delantero brasile\u00f1o registrando solo seis goles en todas las competiciones.<\/p>\n\n\n\n<p>El sudamericano nunca ha sido el m\u00e1s prol\u00edfico, pero en Anfield ha habido un notable baj\u00f3n en la 2020-21.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Roberto Firmino&#39;s goal involvements in all competitions for Liverpool \ud83d\udcc9 <a href=\"https:\/\/t.co\/ynvQOPUbel\">pic.twitter.com\/ynvQOPUbel<\/a><\/p>&mdash; Football Daily (@footballdaily) <a href=\"https:\/\/twitter.com\/footballdaily\/status\/1382669268656005121?ref_src=twsrc%5Etfw\">April 15, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Firmino ha prometido hacer todo lo posible para recuperar su chispa y hacer que el equipo de J\u00fcrgen Klopp vuelva a funcionar.<\/p>\n\n\n\n<p>En declaraciones a <em><a href=\"https:\/\/www.espn.com.br\/futebol\/artigo\/_\/id\/8467077\/a-espn-brasil-firmino-diz-que-sucesso-arrebatador-de-2019-20-hoje-atrapalha-liverpool-todo-mundo-passou-a-jogar-recuado-contra-a-gente\" target=\"_blank\" rel=\"noreferrer noopener\">ESPN Brasil<\/a><\/em>, Firmino admiti\u00f3: \u00abHa sido una temporada dif\u00edcil para m\u00ed. Hay que ser sinceros, no falta la esperanza de mejorar. Mi deseo es evolucionar y crecer cada d\u00eda. No me falta motivaci\u00f3n\u00bb<\/p>\n\n\n\n<p>\u00abMe reto mucho a m\u00ed mismo. S\u00e9 que no estoy en mi mejor momento en comparaci\u00f3n con los \u00faltimos a\u00f1os. Siempre quiero estar ayudando con goles y asistencias, pero eso no ha estado sucediendo desafortunadamente\u00bb.<\/p>\n\n\n\n<p>\u00abNo me rindo. Siempre busco mejorar para ayudar a mi equipo a ser mejor, junto con el grupo. Tengo que evolucionar d\u00eda a d\u00eda\u00bb.<\/p>\n\n\n\n<p>El vigente campe\u00f3n de la <em><a href=\"http:\/\/El vigente campe\u00f3n de la Premier League ha sufrido un descenso colectivo de nivel esta temporada.  Firmino reconoce que el Liverpool ha perdido el rumbo, con una serie de lesiones inoportunas que conspiran contra ellos.\">Premier League<\/a><\/em> ha sufrido un descenso colectivo de nivel esta temporada.<\/p>\n\n\n\n<p>Firmino reconoce que el Liverpool ha perdido el rumbo debido a una serie de lesiones en su plantilla.<\/p>\n\n\n\n<p>\u00abPara nuestro equipo en general, la temporada no ha sido tan buena como el a\u00f1o pasado, pero tenemos que encontrar la manera de continuar\u00bb, a\u00f1adi\u00f3 Firmino.<\/p>\n\n\n\n<p>\u00abNuestros rivales de hoy nos miran de forma diferente. Por supuesto, siempre nos han respetado, pero hoy se han replegado muy defensivamente. A veces es muy dif\u00edcil para nosotros entrar y marcar goles\u00bb.<\/p>\n\n\n\n<p>\u00abTenemos que seguir luchando. Tenemos que luchar por la clasificaci\u00f3n para la Champions League a trav\u00e9s de la Premier League\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.<\/p>\n","protected":false},"author":1022,"featured_media":-101101263441,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[275,77,3757],"enet_tags":{"team":["8650"],"league":["47"],"player":["242709"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Firmino sobre su forma en el Liverpool esta temporada<\/title>\n<meta name=\"description\" content=\"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firmino sobre su forma en el Liverpool esta temporada\" \/>\n<meta property=\"og:description\" content=\"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-16T12:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/\",\"name\":\"Firmino sobre su forma en el Liverpool esta temporada\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#primaryimage\"},\"datePublished\":\"2021-04-16T12:25:54+00:00\",\"dateModified\":\"2021-04-16T12:25:54+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firmino sobre su forma en el Liverpool esta temporada\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firmino sobre su forma en el Liverpool esta temporada","description":"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/","og_locale":"es_ES","og_type":"article","og_title":"Firmino sobre su forma en el Liverpool esta temporada","og_description":"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-04-16T12:25:54+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg","height":683,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/","name":"Firmino sobre su forma en el Liverpool esta temporada","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#primaryimage"},"datePublished":"2021-04-16T12:25:54+00:00","dateModified":"2021-04-16T12:25:54+00:00","author":{"@id":""},"description":"El delantero de los Reds admite que ha tenido problemas esta temporada, pero est\u00e1 decidido a recuperar su chispa.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/firmino-sobre-su-forma-en-el-liverpool-esta-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Firmino sobre su forma en el Liverpool esta temporada"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1303202766.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15325"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1022"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15325"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101263441"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}