{"id":15296,"date":"2021-04-15T22:49:33","date_gmt":"2021-04-15T20:49:33","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=15296"},"modified":"2021-04-15T22:49:38","modified_gmt":"2021-04-15T20:49:38","slug":"alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/","title":{"rendered":"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro"},"content":{"rendered":"\n<h2 id=\"h-con-su-futuro-en-los-spurs-a-n-en-el-aire-harry-kane-acaba-de-recibir-un-s-lido-consejo-de-uno-de-los-pocos-que-realmente-puede-hacerlo-alan-shearer\">Con su futuro en los Spurs a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.<\/h2>\n\n\n\n<p>Harry Kane no deber\u00eda aceptar consejos de nadie, pero recibirlos de Alan Shearer es una historia completamente diferente. La antigua estrella de la Premier League sigue siendo el m\u00e1ximo goleador de la historia del torneo. Que Harry Kane deje el f\u00fatbol ingl\u00e9s es lo mejor que le puede pasar en cuanto a su ego personal. Pero Alan Shearer nunca ha tenido celos de los jugadores que pueden batir sus r\u00e9cords. No hace mucho, se emocion\u00f3 por el r\u00e9cord de triples de Sergio Ag\u00fcero en la Premier League.<\/p>\n\n\n\n<p>En cuanto a dar consejos al capit\u00e1n de Inglaterra, Shearer quiere ser lo m\u00e1s claro posible al respecto. Su plan es apurar al delantero del Tottenham Hotspur para que tome la mejor <em><a href=\"https:\/\/acefootball.com\/football-news\/report-harry-kane-just-made-the-transfer-decision-of-his-life\/\" target=\"_blank\" rel=\"noreferrer noopener\">decisi\u00f3n <\/a><\/em>sobre su futuro. Reconozc\u00e1moslo, Kane no se est\u00e1 haciendo m\u00e1s joven y deber\u00eda tener alg\u00fan t\u00edtulo para un jugador de su categor\u00eda. El pr\u00f3ximo verano ser\u00e1 extremadamente importante para Harry y el Tottenham Hotspur.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Harry Kane will have a great career regardless of whether he stays at Tottenham or leaves. <br><br>But his hunger is why he\u2019s come to a crossroads and tough decision ahead. <br><br>My column for <a href=\"https:\/\/twitter.com\/TheAthleticUK?ref_src=twsrc%5Etfw\">@theathleticuk<\/a><a href=\"https:\/\/t.co\/AiA0Ds1jTj\">https:\/\/t.co\/AiA0Ds1jTj<\/a><\/p>&mdash; Alan Shearer (@alanshearer) <a href=\"https:\/\/twitter.com\/alanshearer\/status\/1382589323120406528?ref_src=twsrc%5Etfw\">April 15, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h3 id=\"h-shearer-quiere-que-kane-siga-su-coraz-n\">Shearer quiere que Kane siga su coraz\u00f3n.<\/h3>\n\n\n\n<p>En una columna escrita para <em><a href=\"https:\/\/theathletic.com\/2519327\/2021\/04\/15\/alan-shearer-harry-kane-will-achieve-greatness-if-he-stays-at-spurs-or-if-he-leaves-but-if-he-wants-out-this-summer-might-be-his-last-chance\/?redirected=1\" target=\"_blank\" rel=\"noreferrer noopener\">The Athletic<\/a><\/em>, esto es lo que escribi\u00f3 Shearer: \u00abTengo demasiado respeto por Harry como jugador y como hombre como para ofrecerle un consejo sobre una decisi\u00f3n que s\u00e9 que para m\u00ed es raramente lineal y que puede, al final, no ser suya. Sin embargo, lo que yo dir\u00eda es lo siguiente: si se va a ir, parece que ser\u00e1 este verano o no se ir\u00e1. Harry cumple 28 a\u00f1os dentro de tres meses y por eso creo que nos acercamos a un momento crucial. Est\u00e1 en su mejor momento, es un art\u00edculo ya hecho, una garant\u00eda absoluta de goles dondequiera que juegue y lo contrario de una apuesta, pero un club comprador va a querer tres o cuatro de sus mejores a\u00f1os a cambio de lo que sin duda ser\u00eda una tarifa de transferencia exorbitante.<\/p>\n\n\n\n<p>\u00abEste es ese momento. Dentro de doce meses ser\u00e1 m\u00e1s dif\u00edcil de justificar\u00bb. La falta de p\u00fablico en su nuevo y hermoso estadio les ha costado, pero eso no significa que vender a Harry tenga sentido financiero. Si quieren volver a la \u00e9lite, necesitar\u00e1n jugadores de su calibre. No pueden dejarle marchar sin encontrar un sustituto, y saben que corren un gran peligro de que se les escape una tarifa una vez que reciban una gran cantidad de dinero por Harry. Tienen que cuidarse\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con su futuro en los Spurs a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer. Harry Kane no deber\u00eda aceptar consejos de nadie, pero recibirlos de Alan Shearer es una historia completamente diferente. La antigua estrella de la Premier League sigue [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101263361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[8341],"tags":[405,297],"enet_tags":{"player":["194165"],"team":["8586"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alan Shearer tiene un mensaje para Harry Kane sobre su futuro<\/title>\n<meta name=\"description\" content=\"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro\" \/>\n<meta property=\"og:description\" content=\"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-15T20:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T20:49:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1311956743.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1311956743.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/\",\"name\":\"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#primaryimage\"},\"datePublished\":\"2021-04-15T20:49:33+00:00\",\"dateModified\":\"2021-04-15T20:49:38+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro","description":"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/","og_locale":"es_ES","og_type":"article","og_title":"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro","og_description":"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-04-15T20:49:33+00:00","article_modified_time":"2021-04-15T20:49:38+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1311956743.jpg","height":667,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1311956743.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/","name":"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#primaryimage"},"datePublished":"2021-04-15T20:49:33+00:00","dateModified":"2021-04-15T20:49:38+00:00","author":{"@id":""},"description":"Con su futuro a\u00fan en el aire, Harry Kane acaba de recibir un s\u00f3lido consejo de uno de los pocos que realmente puede hacerlo: Alan Shearer.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/alan-shearer-tiene-un-mensaje-para-harry-kane-sobre-su-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Alan Shearer tiene un mensaje para Harry Kane sobre su futuro"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/04\/GettyImages-1311956743.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15296"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=15296"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/15296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101263361"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=15296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=15296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=15296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}