{"id":13936,"date":"2021-03-05T13:26:54","date_gmt":"2021-03-05T13:26:54","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=13936"},"modified":"2021-03-05T13:26:54","modified_gmt":"2021-03-05T13:26:54","slug":"klopp-confirma-la-lesion-de-uno-de-sus-jugadores","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/","title":{"rendered":"Klopp confirma la lesi\u00f3n de uno de sus jugadores"},"content":{"rendered":"\n<h2 id=\"h-el-entrenador-de-los-reds-ha-confirmado-otra-lesi-n-de-cara-al-partido-de-la-premier-league-contra-el-fulham-este-fin-de-semana\">El entrenador de los &#8216;Reds&#8217; ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana. <\/h2>\n\n\n\n<p>Ozan Kabak se ha lesionado antes de jugar el partido en Anfield. El centrocampista, que lleg\u00f3 cedido en enero procedente del Schalke, jug\u00f3 los 90 minutos del partido contra el Chelsea (<em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/liverpool-0-1-chelsea-valoracion-de-los-jugadores\/\">1-0<\/a><\/em>) el jueves. Sufri\u00f3 un golpe durante el encuentro y ahora es duda para este fin de semana.<\/p>\n\n\n\n<p>J\u00fcrgen Klopp ha confirmado su lesi\u00f3n pero no puede descartar a Kabak hasta que no se conozca la totalidad de la lesi\u00f3n. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Ozan Kabak has picked up an injury.<br><br>Another centre-back problem for Liverpool.<br><br>Unbelievable.<br><br>\ud83e\udd2f <a href=\"https:\/\/t.co\/FIEHdARcwS\">https:\/\/t.co\/FIEHdARcwS<\/a><\/p>&mdash; Goal (@goal) <a href=\"https:\/\/twitter.com\/goal\/status\/1367808280328867842?ref_src=twsrc%5Etfw\">March 5, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>\u00abOzan tuvo ayer un peque\u00f1o problema tras el partido. Ha jugado muchos partidos y tenemos que ver si est\u00e1 listo para enfrentar al Fulham\u00bb, dijo Klopp en la <em><a href=\"https:\/\/www.liverpoolfc.com\/news\/first-team\/427950-jurgen-klopp-ozan-kabak-nat-phillips-ben-davies-injury-fitness-fulham\" target=\"_blank\" rel=\"noreferrer noopener\">rueda de prensa tras el partido<\/a><\/em>. <\/p>\n\n\n\n<p>\u00abNo parece que sea el caso, pero tendremos que buscar soluciones\u00bb.<\/p>\n\n\n\n<p>Virgil van Dijk, Joe G\u00f3mez y Joel Matip siguen de baja por lesi\u00f3n. Nat Phillips, por su parte, se perdi\u00f3 el partido contra el Chelsea por un ligero golpe, pero se espera que est\u00e9 disponible para el domingo junto con el fichaje de enero, Ben Davies.<\/p>\n\n\n\n<p>\u00abCreo que Nat estar\u00e1 listo y Ben tambi\u00e9n\u00bb, confirm\u00f3 Klopp.<\/p>\n\n\n\n<p>\u00abPara Ben no es f\u00e1cil; lleg\u00f3 nuevo y se tiene que adaptar y asentar. Es muy buen jugador\u00bb.<\/p>\n\n\n\n<p>\u00abSi traes a un jugador nuevo, y luego a un segundo jugador, lo cambia todo. Tenemos que ver qu\u00e9 decisi\u00f3n tomamos\u00bb.<\/p>\n\n\n\n<p>\u00abParece que de los chicos que estaban disponibles &#8211; y no tengo todav\u00eda toda la informaci\u00f3n, solo ayer despu\u00e9s del encuentro &#8211; el partido podr\u00eda ser demasiado r\u00e1pido para Ozan, pero Nat debe estar listo de nuevo y Ben\u00bb.<\/p>\n\n\n\n<p>Otro centrocampista ser\u00eda Fabinho, que jug\u00f3 como defensa central junto a Kabak en el partido contra el Chelsea. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-ace-football-espanol wp-block-embed-ace-football-espanol\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"f7hbdVQFZX\"><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/kabak-sobre-como-van-dijk-le-ha-ayudado-a-adaptarse-en-el-liverpool\/\">Kabak sobre c\u00f3mo Van Dijk le ha ayudado a adaptarse en el Liverpool<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abKabak sobre c\u00f3mo Van Dijk le ha ayudado a adaptarse en el Liverpool\u00bb \u2014 Ace Football Espa\u00f1ol\" src=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/kabak-sobre-como-van-dijk-le-ha-ayudado-a-adaptarse-en-el-liverpool\/embed\/#?secret=f7hbdVQFZX\" data-secret=\"f7hbdVQFZX\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El entrenador de los &#8216;Reds&#8217; ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana. <\/p>\n","protected":false},"author":1022,"featured_media":-101101258520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[1758,275,8410,77],"enet_tags":{"player":["78660","845990"],"team":["8650"],"league":["47"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Klopp confirma la lesi\u00f3n de uno de sus jugadores<\/title>\n<meta name=\"description\" content=\"El entrenador de los &#039;Reds&#039; ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klopp confirma la lesi\u00f3n de uno de sus jugadores\" \/>\n<meta property=\"og:description\" content=\"El entrenador de los &#039;Reds&#039; ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-05T13:26:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/\",\"name\":\"Klopp confirma la lesi\u00f3n de uno de sus jugadores\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#primaryimage\"},\"datePublished\":\"2021-03-05T13:26:54+00:00\",\"dateModified\":\"2021-03-05T13:26:54+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"El entrenador de los 'Reds' ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klopp confirma la lesi\u00f3n de uno de sus jugadores\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klopp confirma la lesi\u00f3n de uno de sus jugadores","description":"El entrenador de los 'Reds' ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/","og_locale":"es_ES","og_type":"article","og_title":"Klopp confirma la lesi\u00f3n de uno de sus jugadores","og_description":"El entrenador de los 'Reds' ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-03-05T13:26:54+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg","height":669,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/","name":"Klopp confirma la lesi\u00f3n de uno de sus jugadores","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#primaryimage"},"datePublished":"2021-03-05T13:26:54+00:00","dateModified":"2021-03-05T13:26:54+00:00","author":{"@id":""},"description":"El entrenador de los 'Reds' ha confirmado otra lesi\u00f3n de cara al partido de la Premier League contra el Fulham este fin de semana.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/klopp-confirma-la-lesion-de-uno-de-sus-jugadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Klopp confirma la lesi\u00f3n de uno de sus jugadores"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/03\/GettyImages-1305381070.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/13936"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1022"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=13936"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/13936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101258520"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=13936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=13936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=13936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}