{"id":13071,"date":"2021-02-11T08:17:44","date_gmt":"2021-02-11T08:17:44","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=13071"},"modified":"2021-02-11T08:17:44","modified_gmt":"2021-02-11T08:17:44","slug":"reaccion-de-guardiola-ante-la-nueva-victoria-del-city","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/","title":{"rendered":"Reacci\u00f3n de Guardiola ante la nueva victoria del City"},"content":{"rendered":"\n<h2 id=\"h-pep-guardiola-ha-felicitado-a-todos-los-jugadores-del-manchester-city-tras-la-victoria-contra-el-swansea-en-la-fa-cup\">Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.<\/h2>\n\n\n\n<p>Lo hizo elogiando a los jugadores y afirmando que eran \u00abincre\u00edbles y especiales\u00bb.<\/p>\n\n\n\n<p>El &#8216;Citizens&#8217; demostr\u00f3 ser mucho para los &#8216;Cisnes&#8217; y acabaron <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/swansea-1-3-manchester-city-valoracion-de-los-jugadores-de-la-fa-cup\/\">ganando 3-1<\/a><\/em> el mi\u00e9rcoles noche. <\/p>\n\n\n\n<p>El City ha ganado 15 partidos seguidos en todas las competiciones, rompiendo el r\u00e9cord que compart\u00eda con el Preston (1891-92) y el Arsenal (1987) por victorias consecutivas en un equipo de primera. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">15. straight. wins.<br><br>Manchester City break the English top-flight record for consecutive wins in all competitions \ud83d\udd25 <a href=\"https:\/\/t.co\/wXt87Q2fKo\">pic.twitter.com\/wXt87Q2fKo<\/a><\/p>&mdash; B\/R Football (@brfootball) <a href=\"https:\/\/twitter.com\/brfootball\/status\/1359583015400312833?ref_src=twsrc%5Etfw\">February 10, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Tambi\u00e9n fue la victoria n\u00ba 200 de Guardiola como entrenador del City, clasific\u00e1ndose a los cuartos de finales de la FA Cup.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Pep Guardiola for Manchester City:<br><br>268 Games <br>200 Wins<br>75% Win Rate<br><br>He could genuinely go down as the GOAT <a href=\"https:\/\/t.co\/0Od9jN8zXQ\">pic.twitter.com\/0Od9jN8zXQ<\/a><\/p>&mdash; Baldiola (@TeacherOfBall) <a href=\"https:\/\/twitter.com\/TeacherOfBall\/status\/1359585543382827017?ref_src=twsrc%5Etfw\">February 10, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Guardiola dijo, v\u00eda <em><a href=\"https:\/\/www.bbc.com\/sport\/live\/football\/55858743\" target=\"_blank\" rel=\"noreferrer noopener\">BBC<\/a><\/em>: \u00abEs impresionante. Hemos venido aqu\u00ed a ganar el partido y eso es lo m\u00e1s importante\u00bb.<\/p>\n\n\n\n<p>\u00abSignifica y demuestra c\u00f3mo de especiales son estos jugadores. S\u00e9 que hemos roto un r\u00e9cord, sobrepasando al Preston y el Arsenal, ahora nos pertenece a nosotros\u00bb.<\/p>\n\n\n\n<p>\u00abY este r\u00e9cord volver\u00e1 a romperse porque el deporte es as\u00ed\u00bb.<\/p>\n\n\n\n<p>\u00abEs mucho y durante este tiempo tan complicado, en navidades y en invierno, hacer lo que nosotros hemos hecho es incre\u00edble\u00bb.<\/p>\n\n\n\n<p>\u00abPero lo importante es que seguimos jugando y nuestra regularidad. Ya estamos pensando en el siguiente partido y tenemos una dura semana por delante, as\u00ed que vamos a ir partido por partido\u00bb.<\/p>\n\n\n\n<p>Sobre su victoria n\u00ba 200 como entrenador Del City, Guardiola admiti\u00f3: \u00abEst\u00e1 bien. Son muchos partidos y muchas victorias. Con suerte, ser\u00e1 el principio de muchas m\u00e1s\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.<\/p>\n","protected":false},"author":1022,"featured_media":-101101255014,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[2199,888,2463],"enet_tags":{"league":["132"],"team":["8456"],"player":["150249"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reacci\u00f3n de Guardiola ante la nueva victoria del City<\/title>\n<meta name=\"description\" content=\"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reacci\u00f3n de Guardiola ante la nueva victoria del City\" \/>\n<meta property=\"og:description\" content=\"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-11T08:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/\",\"name\":\"Reacci\u00f3n de Guardiola ante la nueva victoria del City\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#primaryimage\"},\"datePublished\":\"2021-02-11T08:17:44+00:00\",\"dateModified\":\"2021-02-11T08:17:44+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reacci\u00f3n de Guardiola ante la nueva victoria del City\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reacci\u00f3n de Guardiola ante la nueva victoria del City","description":"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/","og_locale":"es_ES","og_type":"article","og_title":"Reacci\u00f3n de Guardiola ante la nueva victoria del City","og_description":"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-02-11T08:17:44+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg","height":683,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/","name":"Reacci\u00f3n de Guardiola ante la nueva victoria del City","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#primaryimage"},"datePublished":"2021-02-11T08:17:44+00:00","dateModified":"2021-02-11T08:17:44+00:00","author":{"@id":""},"description":"Pep Guardiola ha felicitado a todos los jugadores del Manchester City tras la victoria contra el Swansea en la FA Cup.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/reaccion-de-guardiola-ante-la-nueva-victoria-del-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reacci\u00f3n de Guardiola ante la nueva victoria del City"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1301427170.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/13071"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1022"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=13071"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/13071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101255014"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=13071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=13071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=13071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}