{"id":12946,"date":"2021-02-09T22:42:11","date_gmt":"2021-02-09T22:42:11","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=12946"},"modified":"2021-02-09T22:42:13","modified_gmt":"2021-02-09T22:42:13","slug":"manchester-united-1-0-west-ham-valoracion-de-los-jugadores","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/","title":{"rendered":"Manchester United 1-0 West Ham &#8211; Valoraci\u00f3n de los jugadores"},"content":{"rendered":"\n<h2 id=\"h-el-manchester-united-y-el-west-ham-se-enfrentaron-en-old-trafford-en-la-quinta-ronda-de-la-fa-cup-tenemos-las-valoraciones-de-los-jugadores\">El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.<\/h2>\n\n\n\n<p>En una tarde nevada en Manchester, dos de los seis mejores equipos de la Premier League saltaron al c\u00e9sped de Old Trafford. El West Ham pudo contar con Tomas Soucek como titular ante el Manchester United despu\u00e9s de que la tarjeta roja que le sac\u00f3 <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/mike-dean-fuera-de-la-premier-league-por-amenazas-de-muerte\/\">Mike Dean<\/a><\/em> fuera anulada por la FA. Adem\u00e1s, Solskjaer decidi\u00f3 conceder a Henderson y Van de Beek una esperada oportunidad.<\/p>\n\n\n\n<p>Sin embargo, el equipo de David Moyes sufri\u00f3 un duro golpe cuando Angelo Ogbonna se lesion\u00f3 en torno al minuto 16. El defensa, que\u00a0<em><a href=\"https:\/\/twitter.com\/whufcphotos\/status\/1359199738902568961\" target=\"_blank\" rel=\"noreferrer noopener\">marc\u00f3\u00a0<\/a><\/em>el gol de la victoria en el minuto 120 hace exactamente cuatro a\u00f1os, sali\u00f3 cojeando del terreno de juego despu\u00e9s de que el golpe de Martial le afectara al pie izquierdo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The follow-through from Anthony Martial&#39;s shot which injured Angelo Ogbonna \ud83e\udd15 <a href=\"https:\/\/t.co\/WQMKKvxlE0\">pic.twitter.com\/WQMKKvxlE0<\/a><\/p>&mdash; Goal (@goal) <a href=\"https:\/\/twitter.com\/goal\/status\/1359227555908366338?ref_src=twsrc%5Etfw\">February 9, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>De hecho, McTominay no tard\u00f3 en demostrar por qu\u00e9 es uno de los hombres fundamentales de Solskjaer. Bruno Fernandes inici\u00f3 una jugada que fue mal despejada por Soucek. Rashford no tard\u00f3 en ceder el bal\u00f3n a un McTominay en plan Flash que la meti\u00f3 en la red al primer toque.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Fingertips \ud83e\udd2f<a href=\"https:\/\/twitter.com\/hashtag\/EmiratesFACup?src=hash&amp;ref_src=twsrc%5Etfw\">#EmiratesFACup<\/a> <a href=\"https:\/\/twitter.com\/WestHam?ref_src=twsrc%5Etfw\">@WestHam<\/a> <a href=\"https:\/\/t.co\/0GzdlpgbVX\">pic.twitter.com\/0GzdlpgbVX<\/a><\/p>&mdash; Emirates FA Cup (@EmiratesFACup) <a href=\"https:\/\/twitter.com\/EmiratesFACup\/status\/1359231724421406722?ref_src=twsrc%5Etfw\">February 9, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>En la segunda mitad, el curso del partido no cambi\u00f3 mucho. El Manchester United tuvo m\u00e1s posesi\u00f3n, pero ninguno de los dos equipos mostr\u00f3 lo suficiente como para asegurar la victoria en el tiempo reglamentario. Sin embargo, la decisi\u00f3n de Solskjaer de sacar a Bruno Fernandes y Scott McTominay cambiar\u00eda por completo la historia del partido.<\/p>\n\n\n\n<p>De hecho, McTominay no tard\u00f3 en demostrar por qu\u00e9 es uno de los principales hombres de Solskjaer. Bruno Fernandes inici\u00f3 una jugada que fue mal despejada por Soucek. Rashford no tard\u00f3 en ceder el bal\u00f3n a un McTominay en plan Flash que la meti\u00f3 en la red al primer toque.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Super Scott McTominay \ud83d\udd25<a href=\"https:\/\/twitter.com\/hashtag\/EmiratesFACup?src=hash&amp;ref_src=twsrc%5Etfw\">#EmiratesFACup<\/a> <a href=\"https:\/\/twitter.com\/ManUtd?ref_src=twsrc%5Etfw\">@ManUtd<\/a> <a href=\"https:\/\/t.co\/ZG3w6Sjhyg\">pic.twitter.com\/ZG3w6Sjhyg<\/a><\/p>&mdash; Emirates FA Cup (@EmiratesFACup) <a href=\"https:\/\/twitter.com\/EmiratesFACup\/status\/1359256287595307009?ref_src=twsrc%5Etfw\">February 9, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Los Red Devils se mostraron bastante seguros durante el resto de la pr\u00f3rroga, e incluso consiguieron causar m\u00e1s problemas en torno a la porter\u00eda de Fabianski. Con esta victoria, el Manchester United pasa a los cuartos de final de la FA Cup.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"LivePostMatchStats\" data-header=\"true\" width=\"440\" data-event-id=\"3510590\" data-card=\"true\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<h4 id=\"h-valoraci-n-de-los-jugadores\">Valoraci\u00f3n de los jugadores<\/h4>\n\n\n\n<p><strong>Manchester United:&nbsp;<\/strong>Henderson (6), Wan-Bissaka (6), Lindelof (5), Maguire (5), Telles (6), Matic (6), Fred (6), Van de Beek (6), Greenwood (7), Rashford (7), Martial (5).<\/p>\n\n\n\n<p><strong>Banca:<\/strong>\u00a0McTominay (7), Fernandes (7), Cavani (5), Shaw (5), Williams (5).<\/p>\n\n\n\n<p><strong>West Ham United:<\/strong>&nbsp;Fabianski (7), Coufal (5), Dawson (6), Ogbonna (4), Cresswell (6), Noble (5), Rice (7), Bowen (6), Soucek (6), Fornals (5), Yarmolenko (6).<\/p>\n\n\n\n<p><strong>Banca:<\/strong>\u00a0Diop (5), Johnson (5), Fredericks (5), Odubeko (5), Benrahma (5), Lanzini (5).<\/p>\n\n\n\n<p>Elige las valoraciones y actuaciones de los jugadores utilizando el widget que aparece a continuaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"PlayerRating\" data-nopadding=\"true\" data-card=\"true\" data-is-open-voting=\"true\" data-show-journalist-rating=\"false\" data-event-id=\"3510590\" data-team-to-display=\"both\" width=\"440\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores. En una tarde nevada en Manchester, dos de los seis mejores equipos de la Premier League saltaron al c\u00e9sped de Old Trafford. El West Ham pudo contar con Tomas [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101254764,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[70],"tags":[2199,206,209],"enet_tags":{"league":["132"],"team":["10260","8654"],"sport_events":[3510590]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores<\/title>\n<meta name=\"description\" content=\"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores\" \/>\n<meta property=\"og:description\" content=\"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-09T22:42:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T22:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1300721278.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/><meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1008\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1300721278.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg\",\"width\":1920,\"height\":1008},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/\",\"name\":\"Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#primaryimage\"},\"datePublished\":\"2021-02-09T22:42:11+00:00\",\"dateModified\":\"2021-02-09T22:42:13+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manchester United 1-0 West Ham &#8211; Valoraci\u00f3n de los jugadores\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores","description":"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/","og_locale":"es_ES","og_type":"article","og_title":"Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores","og_description":"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-02-09T22:42:11+00:00","article_modified_time":"2021-02-09T22:42:13+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1300721278.jpg","height":683,"width":1024},{"width":1920,"height":1008,"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1300721278.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/sites\/3\/2021\/02\/1300721278.jpg","width":1920,"height":1008},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/","name":"Manchester United 1-0 West Ham - Valoraci\u00f3n de los jugadores","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#primaryimage"},"datePublished":"2021-02-09T22:42:11+00:00","dateModified":"2021-02-09T22:42:13+00:00","author":{"@id":""},"description":"El Manchester United y el West Ham se enfrentaron en Old Trafford en la quinta ronda de la FA Cup. Tenemos las valoraciones de los jugadores.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-1-0-west-ham-valoracion-de-los-jugadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Manchester United 1-0 West Ham &#8211; Valoraci\u00f3n de los jugadores"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/02\/GettyImages-1300721278.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/12946"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=12946"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/12946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101254764"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=12946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=12946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=12946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}