{"id":11918,"date":"2021-01-27T14:00:50","date_gmt":"2021-01-27T14:00:50","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=11918"},"modified":"2021-01-27T14:00:51","modified_gmt":"2021-01-27T14:00:51","slug":"manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/","title":{"rendered":"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n"},"content":{"rendered":"\n<h2 id=\"h-ace-football-realiza-una-vista-previa-al-partido-de-la-premier-league-entre-el-manchester-city-y-sheffield-united-y-ofrece-consejos-de-apuestas-cuotas-alineaciones-y-noticias-del-equipo\">Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.<\/h2>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"MatchInfoWithOddsV2\" data-nopadding=\"true\" data-across-all-tournaments=\"false\" data-limit=\"5\" width=\"900\" data-event-id=\"3411542\" data-provider=\"comeon\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p>El Manchester United recibe al Sheffield United en Old Trafford el mi\u00e9rcoles con la esperanza de recuperar el primer puesto en la Premier League.<\/p>\n\n\n\n<p>Tras la <em><a href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/west-brom-0-5-manchester-city-valoracion-de-los-jugadores-de-la-premier-league\/\">victoria 5-0<\/a><\/em> del Manchester frente al West Brom, los &#8216;Red Devils&#8217; son segundos en la tabla de la liga. Sin embargo, pueden deshacerlo al vencer al Sheffield United, que se encuentra al final de la tabla con solo cinco puntos en 19 partidos.<\/p>\n\n\n\n<p>Los equipos se enfrentaron hace un mes en Bramall Lane, donde el Manchester <em><a href=\"https:\/\/www.bbc.com\/sport\/football\/55255038\" target=\"_blank\" rel=\"noreferrer noopener\">venci\u00f3 3-2<\/a><\/em> ganando as\u00ed ocho veces en los \u00faltimos nueve partidos (1 empate). Y dadas sus formas muy diferentes, se espera un resultado similar en \u2018The Theatre of Dreams\u2019.<\/p>\n\n\n\n<h3 id=\"h-forma-y-estad-stica-del-manchester-united\">Forma y estad\u00edstica del Manchester United<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"FormOneTeamSnap\" data-nopadding=\"true\" data-side=\"both\" width=\"900\" data-team-id=\"10260\" data-tt-id=\"\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p>El equipo de Ole Gunnar Solskjaer ha ganado cuatro veces en cinco partidos tras <em><a href=\"https:\/\/acefootball.com\/football-news\/manchester-united-3-2-liverpool-fa-cup-player-ratings\/\">ganar 3-2 al Liverpool<\/a><\/em> en la cuarta ronda de la FA Cup. El siempre impresionante Bruno Fernandes anot\u00f3 el gol de la victoria, elevando su cuenta a 16 goles y 10 asistencias en solo 29 partidos.\u00a0Y a pesar de su tiempo de juego constante, el jugador de 26 a\u00f1os no tiene planes de tomarse un descanso.<\/p>\n\n\n\n<p>Es f\u00e1cil ver por qu\u00e9 no desea hacerlo, el Manchester United ha perdido uno de sus \u00faltimos 13 partidos en todas las competiciones (9 victorias y 3 empates). Tambi\u00e9n invictos en la Premier League (10 victorias y 3 empates), son la amenaza del t\u00edtulo.<\/p>\n\n\n\n<p>Los &#8216;Red Devils&#8217; han superado sus luchas en casa al principio de la temporada, habiendo ganado cuatro de sus \u00faltimos cinco partidos de liga en Old Trafford.\u00a0Claramente han acertado, especialmente en el ataque, y con la calidad de sus sustitutos. <\/p>\n\n\n\n<p><strong>Estad\u00edsticas claves del equipo<\/strong><\/p>\n\n\n\n<ul><li>Invictos en sus \u00faltimos 13 partidos de liga (10 victorias y 3 empates).<\/li><li>Ganaron 8 de los \u00faltimos 9 partidos contra Sheffield United en todas las competiciones (1 empate).<\/li><li>Las 3 derrotas de liga han sido en Old Trafford.<\/li><li>Bruno Fernandes ha proporcionado 26 contribuciones de gol (16 goles y 10 asistencias) en solo 29 partidos en todas las competiciones.<\/li><li>No han perdido un partido de liga contra un club que se encuentre al final de la clasificaci\u00f3n desde diciembre de 2011.  <\/li><\/ul>\n\n\n\n<h3 id=\"h-forma-y-estad-stica-de-sheffield-united\">Forma y estad\u00edstica de Sheffield United<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"FormOneTeamSnap\" data-nopadding=\"true\" data-side=\"both\" width=\"900\" data-team-id=\"8657\" data-tt-id=\"\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p>Los &#8216;Blades&#8217; han sufrido una dram\u00e1tica ca\u00edda en su forma. Despu\u00e9s de terminar en el noveno lugar y cinco puntos fuera de un lugar de clasificaci\u00f3n de la Europa League en 2019\/20, los visitantes se ubican \u00faltimos en la clasificaci\u00f3n de la liga para esta temporada. <\/p>\n\n\n\n<p>La presi\u00f3n est\u00e1 pasando factura mientras Sheffield intenta desesperadamente mantener su estatus de m\u00e1xima categor\u00eda por tercera campa\u00f1a consecutiva. Han perdido 16 de sus 19 partidos hasta ahora, y su victoria 1-0 sobre Newcastle el 12 de enero marc\u00f3 su \u00fanico triunfo en la Premier League.<\/p>\n\n\n\n<p>Sin embargo, teniendo en cuenta las recientes victorias de la FA Cup sobre Bristol Rovers y Plymouth, el equipo de Chris Wilder ha ganado tres de sus \u00faltimos cuatro partidos.\u00a0La mayor\u00eda de ellos puede haber sido un club de ligas inferiores, pero a\u00fan representa su mejor forma.<\/p>\n\n\n\n<p><strong>Estad\u00edsticas claves del equipo <\/strong><\/p>\n\n\n\n<ul><li>Perdieron 16 de 19 partidos de liga (1 victoria y 2 empates).<\/li><li>Sin victorias en sus \u00faltimos 15 partidos de liga fuera de casa (3 empates y 12 derrotas).<\/li><li>Sin victorias en los \u00faltimos 10 partidos con el Manchester United en todas las competiciones.<\/li><li>No marcaron en 6 de sus \u00faltimos 7 viajes a Manchester United.<\/li><\/ul>\n\n\n\n<h3 id=\"h-noticias-del-equipos\">Noticias del equipos<\/h3>\n\n\n\n<p><strong>Manchester United<\/strong><br><strong>Fuera: <\/strong>Marcos Rojo, Phil Jones.<br><strong>Dudas:\u00a0<\/strong>Brandon Williams.<\/p>\n\n\n\n<p><strong>Sheffield United<\/strong><br><strong>Fuera: <\/strong>Sander Berge, Jack O&#8217;Connell, Jack Robinson, Ben Osborn, Oliver McBurnie, John Egan.<br><strong>Dudas:\u00a0<\/strong>Lys Mousset.<\/p>\n\n\n\n<h3 id=\"h-alineaciones\">Alineaciones<\/h3>\n\n\n\n<p>(<strong>Nota:<\/strong>\u00a0la imagen cambiar\u00e1 al XI oficial una vez que se anuncien ambos).<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"Lineup\" data-show-bench=\"true\" data-provider=\"enet\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p>Mejores goleadores de la Premier League<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"TopScorersLastMatches\" data-limit=\"5\" data-side=\"both\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<h3 id=\"h-r-cord-cara-a-cara\">R\u00e9cord cara a cara<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"H2HTeams\" width=\"100%\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p>A continuaci\u00f3n se muestran algunas estad\u00edsticas de cara a cara sobre la forma reciente de cada equipo en la Premier League.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"EventTeamsLatestMatchesOutcomesCompare\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<p> <\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"EventTeamsOUStatsCompare\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"EventTeamsLatestStatsCompare\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<h3 id=\"h-informaci-n-sobre-el-partido\">Informaci\u00f3n sobre el partido<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"EventTeamFunStats\" data-nopadding=\"true\" data-fault=\"2\" data-limit=\"10\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<h3 id=\"h-consejos-de-apuestas\">Consejos de apuestas<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"TeamWDLFunStats\" data-fault=\"2\" data-limit=\"10\" data-provider=\"comeon\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"TeamOverUnderFunStats\" data-fault=\"2\" data-limit=\"10\" data-provider=\"betfair\" width=\"900\" data-event-id=\"3411542\" data-theme-appearance=\"dark\"><\/si-lb-widget><\/div>\n\n\n\n<h3 id=\"h-mas-cuotas\">Mas cuotas<\/h3>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"AutomatedMatchBanner\" data-nopadding=\"true\" data-provider=\"comeon\" data-ad-size=\"WRHR\" data-delay=\"10000\" data-transparent=\"true\" width=\"440\"><\/si-lb-widget><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.<\/p>\n","protected":false},"author":1022,"featured_media":-101101252023,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[66],"tags":[8344,206,205,77,4360],"enet_tags":{"player":["510644","251827"],"team":["10260","8657"],"league":["47"],"sport_events":[3411542]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n<\/title>\n<meta name=\"description\" content=\"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T14:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T14:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1008\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/\",\"name\":\"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#primaryimage\"},\"datePublished\":\"2021-01-27T14:00:50+00:00\",\"dateModified\":\"2021-01-27T14:00:51+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n","description":"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/","og_locale":"es_ES","og_type":"article","og_title":"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n","og_description":"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-01-27T14:00:50+00:00","article_modified_time":"2021-01-27T14:00:51+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg","height":1008,"width":1920}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/","name":"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#primaryimage"},"datePublished":"2021-01-27T14:00:50+00:00","dateModified":"2021-01-27T14:00:51+00:00","author":{"@id":""},"description":"Ace Football realiza una vista previa al partido de la Premier League entre el Manchester City y Sheffield United, y ofrece consejos de apuestas, cuotas, alineaciones y noticias del equipo.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/manchester-united-vs-sheffield-united-adelanto-consejos-de-apuestas-estadisticas-y-prediccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Manchester United vs Sheffield United: adelanto, consejos de apuestas, estad\u00edsticas y predicci\u00f3n"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/preview-270121.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/11918"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1022"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=11918"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/11918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101252023"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=11918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=11918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=11918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}