{"id":11346,"date":"2021-01-19T22:02:23","date_gmt":"2021-01-19T22:02:23","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=11346"},"modified":"2021-01-19T22:02:25","modified_gmt":"2021-01-19T22:02:25","slug":"huntelaar-regresa-al-schalke-en-un-traspaso-gratuito","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/","title":{"rendered":"Huntelaar regresa al Schalke en un traspaso gratuito"},"content":{"rendered":"\n<h2 id=\"h-klaas-jan-huntelaar-ha-sido-anunciado-oficialmente-como-jugador-del-schalke-04-despu-s-de-firmar-un-acuerdo-de-transferencia-gratuita\">Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.<\/h2>\n\n\n\n<p>Casi cuatro a\u00f1os despu\u00e9s de su partida de Alemania, \u00abEl Cazador\u00bb est\u00e1 de vuelta en la Bundesliga. El delantero de 37 a\u00f1os fue anunciado como el nuevo jugador del Schalke en su intento de evitar un sorprendente descenso esta temporada.<\/p>\n\n\n\n<p>El Schalke ocupa actualmente el \u00faltimo lugar en la liga alemana, ya que los Royal Blues s\u00f3lo han logrado ganar un partido de sus \u00faltimos 32 encuentros. Tras su <em><a href=\"https:\/\/acefootball.com\/football-news\/schalke-had-hoppe-to-break-a-30-match-run-without-a-win\/\">reciente victoria <\/a><\/em>contra el Hoffenheim, el club de Gelsenkirchen ha recuperado sus esperanzas para el 2021.<\/p>\n\n\n\n<p>Ahora, los aficionados del Schalke pueden emocionarse con el regreso de una de sus antiguas estrellas al club. Huntelaar ha firmado un acuerdo con el equipo alem\u00e1n hasta el final de la temporada, aunque no se han revelado m\u00e1s detalles del contrato.<\/p>\n\n\n\n<p>\u00abNecesitamos ganar partidos y marcar goles para subir en la tabla\u00bb, <em><a href=\"https:\/\/schalke04.de\/en\/team\/klaas-jan-huntelaar-returns-to-fc-schalke-04\/\" target=\"_blank\" rel=\"noreferrer noopener\">dijo <\/a><\/em>Huntelaar. \u00abQuiero hacer mi parte en el club manteni\u00e9ndome en pie. El Schalke pertenece a la Bundesliga y es nuestra responsabilidad asegurarnos de que nos quedemos aqu\u00ed.\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Klaas-Jan Huntelaar&#39;s 2011-12 season at Schalke 04 was ridiculous:<br><br>\u25c9 48 games<br>\u25c9 48 goals<br><br>The Hunter is back. \ud83d\udc99 <a href=\"https:\/\/t.co\/a6uhwGA5gA\">pic.twitter.com\/a6uhwGA5gA<\/a><\/p>&mdash; Squawka Football (@Squawka) <a href=\"https:\/\/twitter.com\/Squawka\/status\/1351586146371989505?ref_src=twsrc%5Etfw\">January 19, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>A pesar de tener 37 a\u00f1os, \u00abEl Cazador\u00bb ya hab\u00eda marcado en siete ocasiones para el Ajax esta temporada. De hecho, el delantero holand\u00e9s anot\u00f3 recientemente un doblete contra el FC Twente en la Eredivise. Con \u00e9l, Huntelaar mantuvo a los actuales campeones en la cima de la liga. Adem\u00e1s, lo hizo tan pronto como entr\u00f3 en el campo, y en s\u00f3lo dos minutos.<\/p>\n\n\n\n<p>Sin embargo, Klaas-Jan no fue una primera opci\u00f3n en el Ajax, especialmente despu\u00e9s de que el club de \u00c1msterdam <em><a href=\"https:\/\/acefootball.com\/football-news\/breaking-ajax-sign-premier-league-ace-on-a-record-e25-million-transfer\/\">hiciera <\/a><\/em>un traspaso de 22,5 millones de euros por S\u00e9bastien Haller. Huntelaar regresa ahora a un club en el que dej\u00f3 un gran legado, con 126 goles y 35 asistencias en 240 partidos con el Schalke.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita. Casi cuatro a\u00f1os despu\u00e9s de su partida de Alemania, \u00abEl Cazador\u00bb est\u00e1 de vuelta en la Bundesliga. El delantero de 37 a\u00f1os fue anunciado como el nuevo jugador del Schalke en su intento de evitar un [&hellip;]<\/p>\n","protected":false},"author":1023,"featured_media":-101101250422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1,8341],"tags":[771,4669],"enet_tags":{"team":["8593","10189"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Huntelaar regresa al Schalke en un traspaso gratuito<\/title>\n<meta name=\"description\" content=\"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huntelaar regresa al Schalke en un traspaso gratuito\" \/>\n<meta property=\"og:description\" content=\"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T22:02:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-19T22:02:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/GettyImages-682644012.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/GettyImages-682644012.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/\",\"name\":\"Huntelaar regresa al Schalke en un traspaso gratuito\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#primaryimage\"},\"datePublished\":\"2021-01-19T22:02:23+00:00\",\"dateModified\":\"2021-01-19T22:02:25+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Huntelaar regresa al Schalke en un traspaso gratuito\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Huntelaar regresa al Schalke en un traspaso gratuito","description":"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/","og_locale":"es_ES","og_type":"article","og_title":"Huntelaar regresa al Schalke en un traspaso gratuito","og_description":"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2021-01-19T22:02:23+00:00","article_modified_time":"2021-01-19T22:02:25+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/GettyImages-682644012.jpg","height":683,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/GettyImages-682644012.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#primaryimage","inLanguage":"es","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/","name":"Huntelaar regresa al Schalke en un traspaso gratuito","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#primaryimage"},"datePublished":"2021-01-19T22:02:23+00:00","dateModified":"2021-01-19T22:02:25+00:00","author":{"@id":""},"description":"Klaas-Jan Huntelaar ha sido anunciado oficialmente como jugador del Schalke 04 despu\u00e9s de firmar un acuerdo de transferencia gratuita.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/huntelaar-regresa-al-schalke-en-un-traspaso-gratuito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Huntelaar regresa al Schalke en un traspaso gratuito"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2021\/01\/GettyImages-682644012.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/11346"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/1023"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=11346"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/11346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101250422"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=11346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=11346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=11346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}