{"id":10566,"date":"2020-11-02T12:36:44","date_gmt":"2020-11-02T12:36:44","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=10566"},"modified":"2020-11-02T12:36:44","modified_gmt":"2020-11-02T12:36:44","slug":"la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/","title":{"rendered":"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz"},"content":{"rendered":"\n<h2 id=\"h-kai-havertz-puede-ser-uno-de-los-jugadores-j-venes-m-s-emocionantes-de-europa-pero-el-chico-nuevo-del-chelsea-a-n-no-se-ha-ganado-a-un-frank-leboeuf-impresionado\">Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.<\/h2>\n\n\n\n<p>Las transferencias de grandes cantidades de dinero generan expectativas desde el principio, sin importar qu\u00e9 tan joven sea un jugador o, especialmente en el caso de Havertz, la necesidad de adaptarse a una nueva liga y pa\u00eds.<\/p>\n\n\n\n<p>Los aplausos le llegaron leg\u00edtimamente a Frank Lampard al fichar al joven de 21 a\u00f1os en septiembre por una tarifa de 80 millones de euros.<\/p>\n\n\n\n<p>El precio puede haber sido alto, pero, considerando el potencial de la ex estrella del Bayer Leverkusen y la cantidad de inter\u00e9s de los clubes de toda Europa, fue un dinero bien gastado a los ojos de los fieles del Blues.<\/p>\n\n\n\n<p>Sin embargo, hasta el d\u00eda de hoy, es evidente que Havertz todav\u00eda se est\u00e1\u00a0<em><a href=\"https:\/\/acefootball.com\/football-news\/lampard-speaks-on-werner-havertzs-struggles-for-chelsea\/\">adaptando a su nuevo entorno<\/a><\/em>.\u00a0Ha mostrado destellos de promesa, incluido un hat-trick de la Copa EFL, pero a\u00fan no ha logrado una consistencia real en Stamford Bridge.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"PlayerSeasonStatsSnap\" data-hide-controls=\"false\" width=\"440\" data-player-id=\"749736\"><\/si-lb-widget><\/div>\n\n\n\n<p>Ahora Frank Leboeuf, quien est\u00e1 lleno de elogios por la llegada veraniega de Havertz, Hakim Ziyech, ha pedido al alem\u00e1n que mejore su juego.<\/p>\n\n\n\n<p>El ex defensor de los Blues le dijo a\u00a0<em><a href=\"https:\/\/www.youtube.com\/watch?v=FU9zzFoxdZk&amp;ab_channel=ESPNFC\" target=\"_blank\" rel=\"noreferrer noopener\">ESPN<\/a><\/em>: \u00abEstoy muy contento por Ziyech, poni\u00e9ndose en forma y dando lo mejor de s\u00ed.\u00a0Pero todav\u00eda no estoy convencido de Havertz, todav\u00eda quiero m\u00e1s de \u00e9l.\u00bb<\/p>\n\n\n\n<p>\u00abQuiero m\u00e1s impacto de \u00e9l donde creo que desaparece.\u00a0Estoy seguro de que Frank todav\u00eda no est\u00e1 completamente satisfecho con la forma en que trabajaron juntos.\u00bb<\/p>\n\n\n\n<p>\u00abA veces parec\u00eda que se buscaban como si realmente no se conocieran.\u00bb<\/p>\n\n\n\n<p>\u00abEstoy buscando algo mejor, mucho mejor del Chelsea.\u00a0Con los jugadores que tienen, son capaces de dar mucho m\u00e1s de lo que vimos.\u00bb<\/p>\n\n\n\n<p>\u00abA pesar de que obtuvieron la victoria, la porter\u00eda a cero, todo iba como ellos quer\u00edan, pero no puedo estar contento con el rendimiento al 100 por ciento.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.<\/p>\n","protected":false},"author":868,"featured_media":-101101237468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[8362],"tags":[1365,1605,77],"enet_tags":{"team":["8455"],"player":["749736"],"league":["47"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz<\/title>\n<meta name=\"description\" content=\"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz\" \/>\n<meta property=\"og:description\" content=\"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T12:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1262\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/\",\"name\":\"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#primaryimage\"},\"datePublished\":\"2020-11-02T12:36:44+00:00\",\"dateModified\":\"2020-11-02T12:36:44+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz","description":"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/","og_locale":"es_ES","og_type":"article","og_title":"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz","og_description":"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-11-02T12:36:44+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg","height":1262,"width":1920}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/","name":"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#primaryimage"},"datePublished":"2020-11-02T12:36:44+00:00","dateModified":"2020-11-02T12:36:44+00:00","author":{"@id":""},"description":"Kai Havertz puede ser uno de los jugadores j\u00f3venes m\u00e1s emocionantes de Europa, pero el chico nuevo del Chelsea a\u00fan no se ha ganado a un Frank Leboeuf impresionado.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/la-leyenda-del-chelsea-envia-una-advertencia-a-kai-havertz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"La leyenda del Chelsea env\u00eda una advertencia a Kai Havertz"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/11\/GettyImages-1281325359.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10566"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/868"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=10566"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101237468"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=10566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=10566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=10566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}