{"id":10318,"date":"2020-10-22T11:20:06","date_gmt":"2020-10-22T11:20:06","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=10318"},"modified":"2020-10-22T11:51:34","modified_gmt":"2020-10-22T11:51:34","slug":"hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/","title":{"rendered":"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n"},"content":{"rendered":"\n<h2 id=\"h-el-delantero-del-borussia-monchengladbach-jonas-hofmann-ha-emitido-su-veredicto-sobre-el-plan-de-juego-del-inter-de-mil-n-en-su-choque-de-la-liga-de-campeones\">El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.<\/h2>\n\n\n\n<p><em><a href=\"https:\/\/acefootball.com\/football-news\/inter-milan-1-2-ac-milan-serie-a-player-ratings\/\">El Inter de Mil\u00e1n empat\u00f3 2-2 en casa ante el Borussia Monchengladbach en su primer partido de la Liga de Campeones el mi\u00e9rcoles por la noche<\/a><\/em>&nbsp;.<\/p>\n\n\n\n<p>Los cuatro goles llegaron en la segunda mitad del juego, con Romelu Lukaku anotando los dos goles de los anfitriones, incluido el empate a los 90 minutos.<\/p>\n\n\n\n<p>Junto con Lautaro Mart\u00ednez, el ex chivo expiatorio del Manchester United ha estado asumiendo la carga de marcar goles para el equipo de Antonio Conte durante las \u00faltimas dos temporadas.<\/p>\n\n\n\n<p>El delantero belga de 27 a\u00f1os ha tenido un buen comienzo en la 2020\/21, acumulando seis goles en cinco salidas en todas las competiciones.<\/p>\n\n\n\n<p>Jonas Hofmann, que casi le da una victoria a Gladbach tras encontrar la red en el minuto 84, ha reflexionado sobre la estrategia de juego del Inter el mi\u00e9rcoles.<\/p>\n\n\n\n<div class=\"wp-block-si-widget wp-block-si-widget--center\"><si-lb-widget widget-id=\"MatchInfoWithOdds\" data-nopadding=\"true\" data-card=\"true\" width=\"440\" data-event-id=\"3461650\"><\/si-lb-widget><\/div>\n\n\n\n<p>\u00abEl Inter intent\u00f3 el 99 por ciento de las veces darle el bal\u00f3n a Lukaku, lo baja y permite que el equipo suba al campo,\u00bb dijo, seg\u00fan lo transmitido por el&nbsp;<em><a href=\"https:\/\/www.football-italia.net\/160914\/hofmann-inter-only-look-lukaku\" target=\"_blank\" rel=\"noreferrer noopener\">Football-Italia<\/a><\/em>.<\/p>\n\n\n\n<p>\u00abFue dif\u00edcil para nosotros ponerle siempre dos hombres encima, uno delante y otro detr\u00e1s.&nbsp;Pero al final, creo que el trabajo que hicimos fue excelente.\u00bb<\/p>\n\n\n\n<p>\u00abEn general, creo que nos merec\u00edamos el punto que ganamos.\u00bb<\/p>\n\n\n\n<p>En el otro partido del Grupo B, el Shakhtar Donetsk sorprendi\u00f3 al Real Madrid en Espa\u00f1a, logrando una sorprendente victoria por 3-2.<\/p>\n\n\n\n<p>Los actuales campeones ucranianos se enfrentar\u00e1n al Inter en casa en la segunda jornada, mientras que Los Blancos se dirigen a Alemania para enfrentarse al Monchengladbach.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.<\/p>\n","protected":false},"author":868,"featured_media":-101101235746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[1],"tags":[3311,82,976,8395,585],"enet_tags":{"team":["9788"],"league":["42"],"player":["331542","181276"],"sport_events":[3461650]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n<\/title>\n<meta name=\"description\" content=\"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n\" \/>\n<meta property=\"og:description\" content=\"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T11:20:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-22T11:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/\",\"name\":\"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#primaryimage\"},\"datePublished\":\"2020-10-22T11:20:06+00:00\",\"dateModified\":\"2020-10-22T11:51:34+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n","description":"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/","og_locale":"es_ES","og_type":"article","og_title":"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n","og_description":"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-10-22T11:20:06+00:00","article_modified_time":"2020-10-22T11:51:34+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg","height":650,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/","name":"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#primaryimage"},"datePublished":"2020-10-22T11:20:06+00:00","dateModified":"2020-10-22T11:51:34+00:00","author":{"@id":""},"description":"El delantero del Borussia Monchengladbach, Jonas Hofmann, ha emitido su veredicto sobre el plan de juego del Inter de Mil\u00e1n en su choque de la Liga de Campeones.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/hofmann-reflexiona-sobre-el-plan-de-juego-del-inter-de-milan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hofmann reflexiona sobre el plan de juego del Inter de Mil\u00e1n"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/GettyImages-1229207561.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10318"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/868"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=10318"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101235746"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=10318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=10318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=10318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}