{"id":10223,"date":"2020-10-19T14:30:32","date_gmt":"2020-10-19T14:30:32","guid":{"rendered":"https:\/\/acefootball.com\/es\/?p=10223"},"modified":"2020-10-20T06:25:23","modified_gmt":"2020-10-20T06:25:23","slug":"las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones","status":"publish","type":"post","link":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/","title":{"rendered":"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones"},"content":{"rendered":"\n<h2 id=\"h-el-liverpool-ya-perdi-a-virgil-van-dijk-durante-un-per-odo-prolongado-y-ahora-se-enfrenta-a-la-posibilidad-de-perder-a-joel-matip\">El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.<\/h2>\n\n\n\n<p>Recientemente, aparecieron im\u00e1genes de video en las redes sociales que muestran al defensa del Liverpool Joel Matip visitando un hospital local despu\u00e9s del derbi de Merseyside del s\u00e1bado.<\/p>\n\n\n\n<p>Luego,&nbsp;<em><a href=\"https:\/\/twitter.com\/_pauljoyce\/status\/1318141104252923905\" target=\"_blank\" rel=\"noreferrer noopener\">The Times<\/a><\/em>&nbsp;confirm\u00f3&nbsp;que Matip se someti\u00f3 a un escaneo despu\u00e9s de recibir un golpe.<\/p>\n\n\n\n<p>El jugador de 29 a\u00f1os regres\u00f3 a la acci\u00f3n en el partido contra el Everton tras perderse el inicio de temporada de su equipo por un problema muscular.&nbsp;Permaneci\u00f3 en los 90 minutos completos, despu\u00e9s de haber jugado por \u00faltima vez la duraci\u00f3n completa de un partido competitivo en octubre de 2019.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">EXCLUSIVE: As revealed last night, Jo\u00ebl Matip left the field on Saturday complaining of an injury &amp; needs a scan to asses the damage. Here he is, arriving at a Liverpool hospital moments ago. I hope to have an update on his condition later &#8211; fingers crossed. <a href=\"https:\/\/twitter.com\/hashtag\/LFC?src=hash&amp;ref_src=twsrc%5Etfw\">#LFC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/exLFCemployee?src=hash&amp;ref_src=twsrc%5Etfw\">#exLFCemployee<\/a> <a href=\"https:\/\/t.co\/9ScFIzh7gp\">pic.twitter.com\/9ScFIzh7gp<\/a><\/p>&mdash; \u26bd\ufe0f\ud83d\udc47\ud83c\udffb (@exLFCemployee03) <a href=\"https:\/\/twitter.com\/exLFCemployee03\/status\/1318122497762611200?ref_src=twsrc%5Etfw\">October 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Afortunadamente, el escaneo no detect\u00f3 ning\u00fan problema importante.&nbsp;Sin embargo, si se tiene en cuenta su historial de lesiones, a\u00fan sigue siendo una duda para el pr\u00f3ximo partido del Liverpool.<\/p>\n\n\n\n<p>Jurgen Klopp ahora debe tomar una decisi\u00f3n crucial sobre si jugar\u00e1 o no con el central camerun\u00e9s en el primer partido de la fase de grupos de la Liga de Campeones contra el Ajax.<\/p>\n\n\n\n<p>En caso de que Matip sea eliminado, Klopp probablemente emparejar\u00e1 a Fabinho y Joe Gomez en la l\u00ednea de fondo, ya que&nbsp;<em><a href=\"https:\/\/acefootball.com\/football-news\/liverpool-issue-update-on-van-dijks-injury\/\">Virgil van Dijk tampoco estar\u00e1 disponible despu\u00e9s de sufrir una lesi\u00f3n que podr\u00eda terminar la temporada<\/a><\/em>&nbsp;.<\/p>\n\n\n\n<p>Otras opciones para los back-four de Klopp incluyen a los j\u00f3venes Nathaniel Phillips, Rhys Williams, Sepp van den Berg y Billy Koumetio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.<\/p>\n","protected":false},"author":868,"featured_media":-101101235232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"push_articles_ronaldo":{"active":false,"canonical":0,"publish":false},"force_updates":null},"categories":[8362],"tags":[8387,275,77],"enet_tags":{"player":["171698"],"team":["8650"],"league":["47"],"sport_events":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones<\/title>\n<meta name=\"description\" content=\"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones\" \/>\n<meta property=\"og:description\" content=\"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Ace Football Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-19T14:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-20T06:25:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"673\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acefootball.com\/es\/#website\",\"url\":\"https:\/\/acefootball.com\/es\/\",\"name\":\"Ace Football Espa\u00f1ol\",\"description\":\"News, Betting and Livescore\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acefootball.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg\",\"contentUrl\":\"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#webpage\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/\",\"name\":\"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones\",\"isPartOf\":{\"@id\":\"https:\/\/acefootball.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#primaryimage\"},\"datePublished\":\"2020-10-19T14:30:32+00:00\",\"dateModified\":\"2020-10-20T06:25:23+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.\",\"breadcrumb\":{\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/acefootball.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones","description":"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/","og_locale":"es_ES","og_type":"article","og_title":"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones","og_description":"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.","og_url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/","og_site_name":"Ace Football Espa\u00f1ol","article_published_time":"2020-10-19T14:30:32+00:00","article_modified_time":"2020-10-20T06:25:23+00:00","og_image":[{"url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg","height":673,"width":1024}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/acefootball.com\/es\/#website","url":"https:\/\/acefootball.com\/es\/","name":"Ace Football Espa\u00f1ol","description":"News, Betting and Livescore","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acefootball.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#primaryimage","inLanguage":"es","url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg","contentUrl":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg"},{"@type":"WebPage","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#webpage","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/","name":"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones","isPartOf":{"@id":"https:\/\/acefootball.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#primaryimage"},"datePublished":"2020-10-19T14:30:32+00:00","dateModified":"2020-10-20T06:25:23+00:00","author":{"@id":""},"description":"El Liverpool ya perdi\u00f3 a Virgil van Dijk durante un per\u00edodo prolongado y ahora se enfrenta a la posibilidad de perder a Joel Matip.","breadcrumb":{"@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/las-preocupaciones-de-klopp-aumentan-a-medida-que-el-liverpool-se-enfrenta-a-otro-susto-por-lesiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acefootball.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las preocupaciones de Klopp aumentan a medida que el Liverpool se enfrenta a otro susto por lesiones"}]},{"@type":"Person","@id":"","url":"https:\/\/acefootball.com\/es\/noticias-de-futbol\/author\/"}]}},"fimg_url":"https:\/\/acefootball.com\/es\/wp-content\/uploads\/2020\/10\/1280729619.jpg","_links":{"self":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10223"}],"collection":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/users\/868"}],"replies":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/comments?post=10223"}],"version-history":[{"count":0,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/posts\/10223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media\/-101101235232"}],"wp:attachment":[{"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/media?parent=10223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/categories?post=10223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acefootball.com\/es\/wp-json\/wp\/v2\/tags?post=10223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}